{"id":6216,"date":"2021-04-10T06:03:50","date_gmt":"2021-04-10T06:03:50","guid":{"rendered":"https:\/\/optionstogrow.com\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\/"},"modified":"2024-12-16T14:13:42","modified_gmt":"2024-12-16T14:13:42","slug":"vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle","status":"publish","type":"post","link":"https:\/\/optionstogrow.com\/fr\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\/","title":{"rendered":"Vous est-il d\u00e9j\u00e0 arriv\u00e9 de faire une erreur qui a d\u00e9g\u00e9n\u00e9r\u00e9 ? Voici comment briser le cycle."},"content":{"rendered":"\n<p class=\"\">Vous \u00eates au milieu d&rsquo;une pr\u00e9sentation importante et une question vous d\u00e9stabilise. Vous essayez de reprendre, mais vous n&rsquo;\u00eates plus dans le coup. Votre public le sent.   <\/p>\n\n<p class=\"\">Vous jouez une partie d&rsquo;\u00e9checs tr\u00e8s serr\u00e9e, vous faites une erreur et perdez votre reine. Dans la pr\u00e9cipitation, votre prochain coup est \u00e9galement mauvais.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2021\/04\/krakenimages-8RXmc8pLX_I-unsplash.jpg?resize=640%2C427&#038;ssl=1\" alt=\"\" class=\"wp-image-1354\" style=\"width:350px\" srcset=\"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2021\/04\/krakenimages-8RXmc8pLX_I-unsplash.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2021\/04\/krakenimages-8RXmc8pLX_I-unsplash.jpg?resize=300%2C200&amp;ssl=1 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption class=\"wp-element-caption\"><sup>Comment briser un mauvais cycle ?<br\/>Photo by <a href=\"https:\/\/unsplash.com\/@krakenimages?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\">krakenimages<\/a> on <a href=\"https:\/\/unsplash.com\/s\/photos\/mistake?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\">Unsplash<\/a><\/sup><\/figcaption><\/figure>\n<\/div>\n<h2 class=\"wp-block-heading\">Pourquoi cela se produit-il ?<\/h2>\n\n<p class=\"\">Le premier faux pas cr\u00e9e un moment de confusion. Nous avons fait une erreur.<br\/><br\/>Pouss\u00e9s par l&rsquo;ego, la peur, la col\u00e8re, notre premi\u00e8re r\u00e9action est de nous pr\u00e9cipiter. Ces \u00e9motions sont rarement de bonnes conseill\u00e8res, et elles transforment souvent une situation complexe, mais encore g\u00e9rable, en une situation chaotique.  <\/p>\n\n<h2 class=\"wp-block-heading\">Comment briser le cycle ?<\/h2>\n\n<ul class=\"wp-block-list\">\n<li class=\"\"><strong>Respirez profond\u00e9ment<\/strong>. Si la situation le permet, fermez les yeux, faites quelques pas, mettez-vous de l&rsquo;eau sur le visage&#8230; faites quelque chose qui vous ram\u00e8ne \u00e0 l&rsquo;instant pr\u00e9sent. <br\/><\/li>\n\n\n\n<li class=\"\"><strong>Reconnaissez votre erreur.<\/strong> Reconnaissez votre erreur. Dites-vous que vous allez la traiter plus tard et en tirer des le\u00e7ons. Si possible, prenez une note rapide de l&rsquo;erreur sur n&rsquo;importe quel support. Cela lib\u00e9rera votre esprit et vous gagnerez en clart\u00e9 sur ce qui doit \u00eatre fait maintenant. Passez du \u00ab\u00a0Pourquoi ai-je fait \u00e7a ?\u00a0\u00bb au \u00ab\u00a0Comment puis-je tirer le meilleur parti de cette situation ?\u00a0\u00bb.   <br\/><\/li>\n\n\n\n<li class=\"\"><strong>Examinez toutes les options qui s&rsquo;offrent \u00e0 vous.<\/strong> Dans de nombreuses situations, nous avons plus d&rsquo;une option. Passez-les en revue rapidement. Votre erreur pr\u00e9c\u00e9dente a chang\u00e9 le contexte. Vous devrez peut-\u00eatre adapter votre plan.   <br\/><\/li>\n\n\n\n<li class=\"\"><strong>R\u00e9fl\u00e9chissez, mais pas trop.<\/strong> La peur peut vous paralyser. Il n&rsquo;est pas utile de ressasser les m\u00eames id\u00e9es. Faites vos diff\u00e9rentes it\u00e9rations et passez \u00e0 l&rsquo;\u00e9tape suivante.  <\/li>\n<\/ul>\n\n<p class=\"\">Ce n&rsquo;est pas la premi\u00e8re erreur qui pose probl\u00e8me &#8211; nous faisons tous des erreurs &#8211; c&rsquo;est la fa\u00e7on dont nous y r\u00e9agissons qui est la cl\u00e9. <br\/>Les leaders qui adoptent un \u00e9tat d&rsquo;esprit de croissance ont 44 % plus de chances d&rsquo;\u00eatre per\u00e7us comme efficaces. (Source : Harvard Business Review) <\/p>\n\n<p class=\"\">Vous pouvez terminer votre pr\u00e9sentation en beaut\u00e9 et transmettre vos id\u00e9es.<br\/>Vous pouvez encore gagner la partie d&rsquo;\u00e9checs.<\/p>\n\n<p class=\"\">Dans un cas complexe, le calme peut vous sauver du chaos.<br\/>Restez calme. Pensez clairement. Relevez-vous plus fort.  <br\/><br\/>Votre avis ? <br\/><br\/>Articles connexes.<br\/><a href=\"https:\/\/optionstogrow.com\/how-to-develop-the-habit-of-believing-in-yourself\/\" target=\"_blank\" rel=\"noreferrer noopener\">Comment prendre l&rsquo;habitude de croire en soi.<\/a><br\/><a href=\"https:\/\/optionstogrow.com\/have-you-ever-heard-about-kimani-maruge\/\" target=\"_blank\" rel=\"noreferrer noopener\">Is it too late to start improving myself?<\/a><br\/><a href=\"https:\/\/optionstogrow.com\/the-one-thing-i-do-to-transform-my-fear-into-energy\/\" target=\"_blank\" rel=\"noreferrer noopener\">The one thing I do to transform my fear into energy.<\/a><br\/><a href=\"https:\/\/optionstogrow.com\/do-you-want-to-achieve-more-sleep-better\/\" target=\"_blank\" rel=\"noreferrer noopener\">Vous voulez en faire plus ? Dormez mieux.<\/a><br\/><a href=\"https:\/\/optionstogrow.com\/the-bad-child-how-can-self-reflection-benefit-you\/\">Le mauvais enfant : Comment l&rsquo;autor\u00e9flexion peut-elle vous \u00eatre b\u00e9n\u00e9fique ?<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous \u00eates au milieu d&rsquo;une pr\u00e9sentation importante et une question vous d\u00e9stabilise. Vous essayez de reprendre, mais vous n&rsquo;\u00eates plus dans le coup. Votre public le sent. Vous jouez une partie d&rsquo;\u00e9checs tr\u00e8s serr\u00e9e, vous faites une erreur et perdez votre reine. Dans la pr\u00e9cipitation, votre prochain coup est \u00e9galement mauvais. Pourquoi cela se produit-il [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2166,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_wp_convertkit_post_meta":{"form":"-1","landing_page":"","tag":"0","restrict_content":"0"},"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[77,84],"tags":[80,76,105,93],"class_list":{"0":"post-6216","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-reflexion-courte","8":"category-reussir-personnellement","9":"tag-apprendre","10":"tag-leadership-fr","11":"tag-responsabilite","12":"tag-se-developper-emotionnellement","13":"entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vous est-il d\u00e9j\u00e0 arriv\u00e9 de faire une erreur qui a d\u00e9g\u00e9n\u00e9r\u00e9 ? Voici comment briser le cycle. - Des options pour se d\u00e9velopper<\/title>\n<meta name=\"description\" content=\"Vous est-il d\u00e9j\u00e0 arriv\u00e9 de faire une erreur qui a d\u00e9g\u00e9n\u00e9r\u00e9 ? Voici comment briser le cycle. Le premier mouvement entra\u00eene un moment de confusion. Pouss\u00e9 par l&#039;ego, la peur, la col\u00e8re, notre premi\u00e8re r\u00e9action est de nous pr\u00e9cipiter.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/optionstogrow.com\/fr\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vous est-il d\u00e9j\u00e0 arriv\u00e9 de faire une erreur qui a d\u00e9g\u00e9n\u00e9r\u00e9 ? Voici comment briser le cycle. - Des options pour se d\u00e9velopper\" \/>\n<meta property=\"og:description\" content=\"Vous est-il d\u00e9j\u00e0 arriv\u00e9 de faire une erreur qui a d\u00e9g\u00e9n\u00e9r\u00e9 ? Voici comment briser le cycle. Le premier mouvement entra\u00eene un moment de confusion. Pouss\u00e9 par l&#039;ego, la peur, la col\u00e8re, notre premi\u00e8re r\u00e9action est de nous pr\u00e9cipiter.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/optionstogrow.com\/fr\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\/\" \/>\n<meta property=\"og:site_name\" content=\"Des options pour se d\u00e9velopper\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Options-To-Grow-109035218181837\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-10T06:03:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-16T14:13:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/optionstogrow.com\/wp-content\/uploads\/2021\/04\/krakenimages-8RXmc8pLX_I-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dror Allouche\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mr_otg\" \/>\n<meta name=\"twitter:site\" content=\"@mr_otg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dror Allouche\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\\\/\"},\"author\":{\"name\":\"Dror Allouche\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#\\\/schema\\\/person\\\/7dd82164ca7481a8c2d59969d4cef9eb\"},\"headline\":\"Vous est-il d\u00e9j\u00e0 arriv\u00e9 de faire une erreur qui a d\u00e9g\u00e9n\u00e9r\u00e9 ? Voici comment briser le cycle.\",\"datePublished\":\"2021-04-10T06:03:50+00:00\",\"dateModified\":\"2024-12-16T14:13:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\\\/\"},\"wordCount\":473,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/krakenimages-8RXmc8pLX_I-unsplash.jpg?fit=640%2C427&ssl=1\",\"keywords\":[\"Apprendre\",\"Leadership\",\"Responsabilit\u00e9\",\"Se d\u00e9velopper \u00e9motionnellement\"],\"articleSection\":[\"R\u00e9flexion courte\",\"R\u00e9ussir personnellement\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\\\/\",\"url\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\\\/\",\"name\":\"Vous est-il d\u00e9j\u00e0 arriv\u00e9 de faire une erreur qui a d\u00e9g\u00e9n\u00e9r\u00e9 ? Voici comment briser le cycle. - Des options pour se d\u00e9velopper\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/krakenimages-8RXmc8pLX_I-unsplash.jpg?fit=640%2C427&ssl=1\",\"datePublished\":\"2021-04-10T06:03:50+00:00\",\"dateModified\":\"2024-12-16T14:13:42+00:00\",\"description\":\"Vous est-il d\u00e9j\u00e0 arriv\u00e9 de faire une erreur qui a d\u00e9g\u00e9n\u00e9r\u00e9 ? Voici comment briser le cycle. Le premier mouvement entra\u00eene un moment de confusion. Pouss\u00e9 par l'ego, la peur, la col\u00e8re, notre premi\u00e8re r\u00e9action est de nous pr\u00e9cipiter.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/krakenimages-8RXmc8pLX_I-unsplash.jpg?fit=640%2C427&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/krakenimages-8RXmc8pLX_I-unsplash.jpg?fit=640%2C427&ssl=1\",\"width\":640,\"height\":427},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vous est-il d\u00e9j\u00e0 arriv\u00e9 de faire une erreur qui a d\u00e9g\u00e9n\u00e9r\u00e9 ? Voici comment briser le cycle.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/\",\"name\":\"Des options pour se d\u00e9velopper\",\"description\":\"Acc\u00e9l\u00e9rer les r\u00e9sultats sur vos projets importants\",\"publisher\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#organization\",\"name\":\"OptionsToGrow\",\"url\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo-web-1-e1597514267714.jpg?fit=96%2C65&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo-web-1-e1597514267714.jpg?fit=96%2C65&ssl=1\",\"width\":96,\"height\":65,\"caption\":\"OptionsToGrow\"},\"image\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Options-To-Grow-109035218181837\",\"https:\\\/\\\/x.com\\\/mr_otg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#\\\/schema\\\/person\\\/7dd82164ca7481a8c2d59969d4cef9eb\",\"name\":\"Dror Allouche\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g\",\"caption\":\"Dror Allouche\"},\"description\":\"Executive who ran a 9-figure business. I left corporate at the age of 46, financially independent. I write to share my learning on how to grow your life, your career, your money.\",\"sameAs\":[\"https:\\\/\\\/optionstogrow.com\\\/\",\"https:\\\/\\\/x.com\\\/mr_otg\"],\"url\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/author\\\/optionstogrow\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vous est-il d\u00e9j\u00e0 arriv\u00e9 de faire une erreur qui a d\u00e9g\u00e9n\u00e9r\u00e9 ? Voici comment briser le cycle. - Des options pour se d\u00e9velopper","description":"Vous est-il d\u00e9j\u00e0 arriv\u00e9 de faire une erreur qui a d\u00e9g\u00e9n\u00e9r\u00e9 ? Voici comment briser le cycle. Le premier mouvement entra\u00eene un moment de confusion. Pouss\u00e9 par l'ego, la peur, la col\u00e8re, notre premi\u00e8re r\u00e9action est de nous pr\u00e9cipiter.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/optionstogrow.com\/fr\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\/","og_locale":"fr_FR","og_type":"article","og_title":"Vous est-il d\u00e9j\u00e0 arriv\u00e9 de faire une erreur qui a d\u00e9g\u00e9n\u00e9r\u00e9 ? Voici comment briser le cycle. - Des options pour se d\u00e9velopper","og_description":"Vous est-il d\u00e9j\u00e0 arriv\u00e9 de faire une erreur qui a d\u00e9g\u00e9n\u00e9r\u00e9 ? Voici comment briser le cycle. Le premier mouvement entra\u00eene un moment de confusion. Pouss\u00e9 par l'ego, la peur, la col\u00e8re, notre premi\u00e8re r\u00e9action est de nous pr\u00e9cipiter.","og_url":"https:\/\/optionstogrow.com\/fr\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\/","og_site_name":"Des options pour se d\u00e9velopper","article_publisher":"https:\/\/www.facebook.com\/Options-To-Grow-109035218181837","article_published_time":"2021-04-10T06:03:50+00:00","article_modified_time":"2024-12-16T14:13:42+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/optionstogrow.com\/wp-content\/uploads\/2021\/04\/krakenimages-8RXmc8pLX_I-unsplash.jpg","type":"image\/jpeg"}],"author":"Dror Allouche","twitter_card":"summary_large_image","twitter_creator":"@mr_otg","twitter_site":"@mr_otg","twitter_misc":{"\u00c9crit par":"Dror Allouche","Dur\u00e9e de lecture estim\u00e9e":"3 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/optionstogrow.com\/fr\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\/#article","isPartOf":{"@id":"https:\/\/optionstogrow.com\/fr\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\/"},"author":{"name":"Dror Allouche","@id":"https:\/\/optionstogrow.com\/fr\/#\/schema\/person\/7dd82164ca7481a8c2d59969d4cef9eb"},"headline":"Vous est-il d\u00e9j\u00e0 arriv\u00e9 de faire une erreur qui a d\u00e9g\u00e9n\u00e9r\u00e9 ? Voici comment briser le cycle.","datePublished":"2021-04-10T06:03:50+00:00","dateModified":"2024-12-16T14:13:42+00:00","mainEntityOfPage":{"@id":"https:\/\/optionstogrow.com\/fr\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\/"},"wordCount":473,"commentCount":0,"publisher":{"@id":"https:\/\/optionstogrow.com\/fr\/#organization"},"image":{"@id":"https:\/\/optionstogrow.com\/fr\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2021\/04\/krakenimages-8RXmc8pLX_I-unsplash.jpg?fit=640%2C427&ssl=1","keywords":["Apprendre","Leadership","Responsabilit\u00e9","Se d\u00e9velopper \u00e9motionnellement"],"articleSection":["R\u00e9flexion courte","R\u00e9ussir personnellement"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/optionstogrow.com\/fr\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/optionstogrow.com\/fr\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\/","url":"https:\/\/optionstogrow.com\/fr\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\/","name":"Vous est-il d\u00e9j\u00e0 arriv\u00e9 de faire une erreur qui a d\u00e9g\u00e9n\u00e9r\u00e9 ? Voici comment briser le cycle. - Des options pour se d\u00e9velopper","isPartOf":{"@id":"https:\/\/optionstogrow.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/optionstogrow.com\/fr\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\/#primaryimage"},"image":{"@id":"https:\/\/optionstogrow.com\/fr\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2021\/04\/krakenimages-8RXmc8pLX_I-unsplash.jpg?fit=640%2C427&ssl=1","datePublished":"2021-04-10T06:03:50+00:00","dateModified":"2024-12-16T14:13:42+00:00","description":"Vous est-il d\u00e9j\u00e0 arriv\u00e9 de faire une erreur qui a d\u00e9g\u00e9n\u00e9r\u00e9 ? Voici comment briser le cycle. Le premier mouvement entra\u00eene un moment de confusion. Pouss\u00e9 par l'ego, la peur, la col\u00e8re, notre premi\u00e8re r\u00e9action est de nous pr\u00e9cipiter.","breadcrumb":{"@id":"https:\/\/optionstogrow.com\/fr\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/optionstogrow.com\/fr\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/optionstogrow.com\/fr\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\/#primaryimage","url":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2021\/04\/krakenimages-8RXmc8pLX_I-unsplash.jpg?fit=640%2C427&ssl=1","contentUrl":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2021\/04\/krakenimages-8RXmc8pLX_I-unsplash.jpg?fit=640%2C427&ssl=1","width":640,"height":427},{"@type":"BreadcrumbList","@id":"https:\/\/optionstogrow.com\/fr\/vous-est-il-deja-arrive-de-faire-une-erreur-qui-a-degenere-voici-comment-briser-le-cycle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/optionstogrow.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Vous est-il d\u00e9j\u00e0 arriv\u00e9 de faire une erreur qui a d\u00e9g\u00e9n\u00e9r\u00e9 ? Voici comment briser le cycle."}]},{"@type":"WebSite","@id":"https:\/\/optionstogrow.com\/fr\/#website","url":"https:\/\/optionstogrow.com\/fr\/","name":"Des options pour se d\u00e9velopper","description":"Acc\u00e9l\u00e9rer les r\u00e9sultats sur vos projets importants","publisher":{"@id":"https:\/\/optionstogrow.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/optionstogrow.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/optionstogrow.com\/fr\/#organization","name":"OptionsToGrow","url":"https:\/\/optionstogrow.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/optionstogrow.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/07\/logo-web-1-e1597514267714.jpg?fit=96%2C65&ssl=1","contentUrl":"https:\/\/i1.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/07\/logo-web-1-e1597514267714.jpg?fit=96%2C65&ssl=1","width":96,"height":65,"caption":"OptionsToGrow"},"image":{"@id":"https:\/\/optionstogrow.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Options-To-Grow-109035218181837","https:\/\/x.com\/mr_otg"]},{"@type":"Person","@id":"https:\/\/optionstogrow.com\/fr\/#\/schema\/person\/7dd82164ca7481a8c2d59969d4cef9eb","name":"Dror Allouche","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g","caption":"Dror Allouche"},"description":"Executive who ran a 9-figure business. I left corporate at the age of 46, financially independent. I write to share my learning on how to grow your life, your career, your money.","sameAs":["https:\/\/optionstogrow.com\/","https:\/\/x.com\/mr_otg"],"url":"https:\/\/optionstogrow.com\/fr\/author\/optionstogrow\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2021\/04\/krakenimages-8RXmc8pLX_I-unsplash.jpg?fit=640%2C427&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcagkH-1Cg","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/posts\/6216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/comments?post=6216"}],"version-history":[{"count":1,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/posts\/6216\/revisions"}],"predecessor-version":[{"id":6217,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/posts\/6216\/revisions\/6217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/media\/2166"}],"wp:attachment":[{"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/media?parent=6216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/categories?post=6216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/tags?post=6216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}