{"id":6091,"date":"2024-11-05T09:01:14","date_gmt":"2024-11-05T09:01:14","guid":{"rendered":"https:\/\/optionstogrow.com\/?p=6091"},"modified":"2024-11-05T15:16:42","modified_gmt":"2024-11-05T15:16:42","slug":"leadership-a-la-lincoln","status":"publish","type":"post","link":"https:\/\/optionstogrow.com\/fr\/leadership-a-la-lincoln\/","title":{"rendered":"Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger"},"content":{"rendered":"\n<p class=\"\">Lincoln on Leadership by Donald T. Phillips&nbsp;<\/p>\n\n\n\n<p class=\"\">Lincoln est consid\u00e9r\u00e9 comme l&rsquo;un des meilleurs pr\u00e9sidents am\u00e9ricains. Le livre de Donald T. Phillips explore non seulement ses actions, mais aussi ses m\u00e9thodes. Il d\u00e9cortique :&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\">Son style de Leadership : communication avec les autres<\/li>\n\n\n\n<li class=\"\">Son caract\u00e8re : \u00e9thique et valeurs<\/li>\n\n\n\n<li class=\"\">Son processus de d\u00e9cision : comment il les prenait.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"\">Pas besoin d&rsquo;\u00eatre pr\u00e9sident pour apprendre des grands leaders et s&rsquo;en inspirer dans sa propre vie.&nbsp;<\/p>\n\n\n\n<p class=\"\">Et comme James M. Kouzes, Barry Z. Posner le disent si bien dans leur livre \u201cThe Truth About Leadership\u201d. Notre monde change tr\u00e8s vite, mais les bons principes de Leadership perdurent.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"\">\u201cCe sont des le\u00e7ons qui \u00e9taient vraies il y a trente ans, qui sont vraies aujourd&rsquo;hui et qui, nous le croyons, seront vraies dans trente ans.\u201d<\/p>\n<\/blockquote>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"287\" height=\"442\" src=\"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2024\/11\/image.png?resize=287%2C442&#038;ssl=1\" alt=\"Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger\" class=\"wp-image-6092\" style=\"width:350px\" srcset=\"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2024\/11\/image.png?w=287&amp;ssl=1 287w, https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2024\/11\/image.png?resize=195%2C300&amp;ssl=1 195w\" sizes=\"auto, (max-width: 287px) 100vw, 287px\" \/><figcaption class=\"wp-element-caption\"><sup>Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger<\/sup><\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger&#8230;<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">I\/ Travailler avec les autres<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Le\u00e7on #1 : Rendez vous accessible<\/h4>\n\n\n\n<p class=\"\">Lincoln consacrait une grande partie de son temps \u00e0 \u00eatre avec ses hommes \u00e0 tous les niveaux. Il \u00e9tait d\u00e9crit comme aimable, accessible, dr\u00f4le, et utilisant un vocabulaire simple et clair. Il s&rsquo;adaptait constamment \u00e0 ses interlocuteurs.&nbsp;<\/p>\n\n\n\n<p class=\"\">M\u00eame si le temps est pr\u00e9cieux, il est essentiel d\u2019en prendre pour \u00e9couter et \u00e9changer avec notre entourage. Une cl\u00e9, pour ne pas avoir l\u2019impression de gaspiller son temps, est d\u2019en faire une priorit\u00e9 dans l\u2019agenda. Choisir nous redonne le contr\u00f4le sur notre temps.&nbsp;&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Le\u00e7on #2 : Tisser des relations fortes avec ses \u00e9quipes directes&nbsp;<\/h4>\n\n\n\n<p class=\"\">Lincoln invitait ses proches collaborateurs \u00e0 la maison. Il allait chez eux. Les conna\u00eetre lui permettait de mieux collaborer.&nbsp;<\/p>\n\n\n\n<p class=\"\">Il tissait \u00e9galement des liens avec ses rivaux, ce qui lui a permis de les rallier \u00e0 sa cause et de les int\u00e9grer \u00e0 son projet.<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">II\/ Leadership \u00e0 la Lincoln : Diriger avec \u00e9thique, le caract\u00e8re<\/h3>\n\n\n\n<p class=\"\"><a href=\"https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/\">Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu&rsquo;ils entreprennent<\/a> est un livre bas\u00e9 sur le d\u00e9veloppement du caract\u00e8re (long terme\/travail de fond) contrairement \u00e0 la majorit\u00e9 des livres qui mettent l&rsquo;accent sur les tactiques (court terme\/travail superficiel). C&rsquo;est certainement ce qui a contribu\u00e9 \u00e0 son succ\u00e8s.&nbsp;<\/p>\n\n\n\n<p class=\"\">Sans surprise, Lincoln travaillait sur son caract\u00e8re. Donald Philips met en avant deux le\u00e7ons dans ce domaine.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Le\u00e7on #1 : Coller \u00e0 ses valeurs<\/h4>\n\n\n\n<h5 class=\"wp-block-heading\">A) Feedback<\/h5>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXespKBxHVw2KAPm9BqsyDB4i3uesN0xBWDS9SRkbW4ZOBsnoRy7fSpKTzYmJ_OQ6ME7ImpAjpg-xr2W5_7OvOvXy2iaOS7RXOaGeMV_D77I9SGAfmtPvHeJoZi_DGKFr6Z6Q_AKBFi7On5O3ubJY4ChMIM?key=hEodIlCxY2N4B9BQ8JoH9y8Y\" alt=\"Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger\" style=\"width:350px\"\/><figcaption class=\"wp-element-caption\">Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"\">Lincoln \u00e9tait connu pour avoir les discussions difficiles et dire la v\u00e9rit\u00e9.\u00a0Et il encourageait les autres \u00e0 faire de m\u00eame.\u00a0<a href=\"https:\/\/optionstogrow.com\/fr\/feedback-reussi-une-methode-en-3-etapes-pour-nos-conversations-difficiles\/\">(pour aller plus loin voir une m\u00e9thode en 3 \u00e9tapes pour nos conversations difficiles)<\/a><\/p>\n\n\n\n<p class=\"\">Je mets le feedback et les parties prenantes au centre de mon <a href=\"https:\/\/optionstogrow.com\/fr\/acceleration-du-leadership-pour-cadres-superieurs\/\">coaching corporate.<\/a><br>Pourquoi ?&nbsp;Parce que cela cr\u00e9e des r\u00e9sultats extraordinaires. Les leaders et leurs \u00e9quipes se transforment.&nbsp;<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">B) Leadership situationnel<\/h5>\n\n\n\n<p class=\"\">Lincoln variait ses approches. Quand ses collaborateurs d\u00e9viaient des valeurs communes, il :&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\">Proposer des suggestions douces<\/li>\n\n\n\n<li class=\"\">Tenter de convaincre<\/li>\n\n\n\n<li class=\"\">N\u2019h\u00e9sitait pas \u00e0 se s\u00e9parer de personnes qui ne partageaient plus ses valeurs<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Le\u00e7on #2 : Rester ma\u00eetre de ses \u00e9motions<\/h4>\n\n\n\n<p class=\"\">Lincoln travaillait sur ses \u00e9motions. Il ne les invitait pas \u00e0 la table de la d\u00e9cision.&nbsp;<\/p>\n\n\n\n<p class=\"\">Il n&rsquo;essayait pas de se faire aimer, mais de faire progresser son plan. <a href=\"https:\/\/optionstogrow.com\/fr\/le-courage-detre-deteste-4-cles-pour-choisir-le-bonheur-et-trouver-sa-liberte\/\">Le point principal du livre The courage to be disliked.&nbsp;<\/a><\/p>\n\n\n\n<p class=\"\">G\u00e9rer ses \u00e9motions participe aussi \u00e0 la culture du Feedback.\u00a0Si je ne m&#8217;emporte pas quand on me propose une suggestion, les gens sont plus enclins \u00e0 m&rsquo;en donner d&rsquo;autres.\u00a0<\/p>\n\n\n\n<p class=\"\">Quand ses \u00e9motions le d\u00e9bordaient, il \u00e9crivait des lettres au destinataire qu&rsquo;il n&rsquo;envoyait jamais ou se confier \u00e0 un proche. \u00c7a peut se comparer \u00e0 \u00e9crire dans <a href=\"https:\/\/optionstogrow.com\/fr\/le-pouvoir-du-journal-comment-surmonter-les-problemes-et-realiser-vos-reves\/\">son journal<\/a> ou travailler avec un <a href=\"https:\/\/optionstogrow.com\/fr\/\">coach<\/a> aujourd&rsquo;hui.&nbsp;<\/p>\n\n\n\n<p class=\"\">Le meilleur exercice que j&rsquo;ai trouv\u00e9 pour apprendre \u00e0 mieux contr\u00f4ler mes \u00e9motions \u201dles questions actives\u00a0\u00bb. <a href=\"https:\/\/optionstogrow.com\/fr\/reussir-a-changer-de-comportement-en-4-etapes\/\">(j\u2019explique ici comment le mettre en pratique.)<\/a><br>Je fais cet exercice quotidiennement depuis plus d\u2019un an. Et vous pouvez observer que les cases ne sont pas toujours vertes. (voir ci-dessous)<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXdadS9LY7kek3BGonHAK6ABVZpfodClAeAEKPVGPYNOLfmlI95vCrVAGI17UZAEo-zmIxsDzPr4xDnkWf023v_H8ID5ppXnXqc4dgvr0jXmZOw9MJKOGyBFIst12LsHSZxN8p_g1G8SO8XDvyR84pCixsuK?key=hEodIlCxY2N4B9BQ8JoH9y8Y\" alt=\"Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger\" style=\"width:350px\"\/><figcaption class=\"wp-element-caption\"><sup>Les questions actives. Un exercice pour changer tout ce que vous souhaitez.<\/sup><br><\/figcaption><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\">III\/ D\u00e9cider<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Le\u00e7on #1 : Consulter ensemble, d\u00e9cider seul<\/h4>\n\n\n\n<p class=\"\">Lincoln consultait constamment, posait des questions, cherchait \u00e0 comprendre.<br>Mais quand venait le moment de d\u00e9cider ; il le faisait seul.&nbsp;<\/p>\n\n\n\n<p class=\"\">Si c\u2019\u00e9tait un succ\u00e8s, il remerciait tous les gens qui l&rsquo;avaient aid\u00e9 et les cr\u00e9diter du r\u00e9sultat. Quand \u00e7a ne fonctionnait pas, il en prenait la responsabilit\u00e9.&nbsp;<\/p>\n\n\n\n<p class=\"\">On ne peut certainement pas dupliquer ce mod\u00e8le dans toutes les situations. Et ce n&rsquo;est pas souhaitable. Mais quand les enjeux sont hauts, quand l&rsquo;\u00e9quipe n&rsquo;arrive pas \u00e0 choisir.&nbsp;C&rsquo;est au leader de prendre la responsabilit\u00e9.&nbsp;<\/p>\n\n\n\n<p class=\"\"><a href=\"https:\/\/winning-writer-6789.ck.page\/2063ed76c8\" target=\"_blank\" rel=\"noreferrer noopener\">D\u00e9couvrez mon Guide ressources : Les 11 livres qui ont le plus influenc\u00e9 ma carri\u00e8re. (Y compris mon pr\u00e9f\u00e9r\u00e9 de toutes les cat\u00e9gories)<\/a><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Le\u00e7on #2 : Planifier et pers\u00e9v\u00e9rer<\/h4>\n\n\n\n<p class=\"\">Cr\u00e9er un plan \u00e0 long terme, engager les \u00e9quipes sur le plan et les valeurs, et pers\u00e9v\u00e9rer a \u00e9t\u00e9 une cl\u00e9 de succ\u00e8s pour Lincoln.&nbsp;<\/p>\n\n\n\n<p class=\"\"><a href=\"https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/\">L&rsquo;habitude N\u00b02 de M. Covey<\/a> est de commencer avec la fin en t\u00eate.&nbsp;Cette approche permet de concentrer son \u00e9nergie sur ce que l&rsquo;on veut et de pers\u00e9v\u00e9rer quand c&rsquo;est difficile.&nbsp;<\/p>\n\n\n\n<p class=\"\">Une approche qu&rsquo;on peut utiliser pour nos projets personnels aussi, comme l\u2019a d\u00e9montr\u00e9 <a href=\"https:\/\/optionstogrow.com\/fr\/comment-trouver-de-la-clarte-pour-reussir-tous-vos-projets\/\">Nolan Archibald<\/a> en devenant le plus jeune PDG d\u2019une entreprise du Fortune 500 en se posant une question.<br><br>\u201cQuelles sont toutes les exp\u00e9riences et tous les probl\u00e8mes que je dois apprendre et ma\u00eetriser pour que ce qui sort \u00e0 l\u2019autre bout soit quelqu\u2019un qui est pr\u00eat et capable de devenir un PDG performant ?\u201d.<\/p>\n\n\n\n<p class=\"\">Pour aller plus loin : <a href=\"https:\/\/optionstogrow.com\/fr\/comment-construire-son-projet-de-vie\/\">Comment construire son projet de vie ?<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n\n\n\n<p class=\"\">Ces le\u00e7ons peuvent vous aider \u00e0 progresser, quel que soit votre activit\u00e9. Le plus difficile n&rsquo;est pas de les comprendre, mais de les appliquer. Comment allez-vous les mettre en pratique dans votre vie ?<\/p>\n\n\n\n<p class=\"\">\u00c0 bient\u00f4t.&nbsp;<br>Dror<\/p>\n\n\n\n<p class=\"\">***<\/p>\n\n\n\n<p class=\"\"><strong>Si vous avez aim\u00e9 cet article<\/strong>, vous aimerez surement ma newsletter en fran\u00e7ais. Rejoignez une communaut\u00e9 de lecteurs ambitieux qui veulent r\u00e9ussir leurs carri\u00e8res tout en profitant de leur vie.&nbsp;<a href=\"https:\/\/optionstogrow.com\/fr\/newsletter\/\"><strong>Inscrivez-vous ici<\/strong><\/a><strong>&nbsp;<\/strong>et recevez l\u00e0 tous les mercredis matin directement dans votre boite mail.<\/p>\n\n\n\n<p class=\"\"><strong>***<\/strong><\/p>\n\n\n\n<p class=\"\"><strong>PS :<\/strong>&nbsp;d\u00e8s que vous \u00eates pr\u00eat, voici 2 autres fa\u00e7ons avec lesquelles je peux vous aider \u00e0 acc\u00e9l\u00e9rer votre croissance gr\u00e2ce au coaching :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\"><strong>Vous \u00eates ambitieux<\/strong>&nbsp;: vous avez d\u00e9j\u00e0 r\u00e9alis\u00e9 beaucoup. Et vous avez l\u2019intention de continuer. Mais cette fois-ci, vous souhaitez le faire tout en profitant des choses importantes dans votre vie.&nbsp;<a href=\"https:\/\/optionstogrow.com\/fr\/travaillez-avec-moi\/\">Curieux\u2026Cliquez ici<\/a>.<\/li>\n\n\n\n<li class=\"\"><strong>Vous dirigez une \u00e9quipe<\/strong>&nbsp;: vous savez qu\u2019une petite am\u00e9lioration dans votre leadership peut avoir d\u2019\u00e9normes impacts sur les r\u00e9sultats de l\u2019\u00e9quipe et donc de votre carri\u00e8re. J\u2019ai \u00e9t\u00e9 form\u00e9 et certifi\u00e9 par le premier ex\u00e9cutif coach au monde Marshall Goldsmith. Je vous accompagne dans votre projet et garantis le r\u00e9sultat. Vous ne me payez que si vous r\u00e9ussissez. Curieux?&nbsp;&nbsp;<a href=\"https:\/\/optionstogrow.com\/11-executive-coaching\/\">Apprenez-en davantage ici.<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_wp_convertkit_post_meta":{"form":"5783834","landing_page":"","tag":"0","restrict_content":"0"},"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[85,84,79],"tags":[80,89,97,78,106],"class_list":{"0":"post-6091","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-blog-fr","7":"category-reussir-personnellement","8":"category-reussir-professionnellement","9":"tag-apprendre","10":"tag-decisions-fr","11":"tag-reussir-personnellement","12":"tag-reussir-professionnellement","13":"tag-succes","14":"entry","15":"has-post-thumbnail"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger - Des options pour se d\u00e9velopper<\/title>\n<meta name=\"description\" content=\"Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/optionstogrow.com\/fr\/leadership-a-la-lincoln\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger - Des options pour se d\u00e9velopper\" \/>\n<meta property=\"og:description\" content=\"Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger\" \/>\n<meta property=\"og:url\" content=\"https:\/\/optionstogrow.com\/fr\/leadership-a-la-lincoln\/\" \/>\n<meta property=\"og:site_name\" content=\"Des options pour se d\u00e9velopper\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Options-To-Grow-109035218181837\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-05T09:01:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-05T15:16:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/optionstogrow.com\/wp-content\/uploads\/2024\/11\/image.png\" \/>\n<meta name=\"author\" content=\"Dror Allouche\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mr_otg\" \/>\n<meta name=\"twitter:site\" content=\"@mr_otg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dror Allouche\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/leadership-a-la-lincoln\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/leadership-a-la-lincoln\\\/\"},\"author\":{\"name\":\"Dror Allouche\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#\\\/schema\\\/person\\\/7dd82164ca7481a8c2d59969d4cef9eb\"},\"headline\":\"Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger\",\"datePublished\":\"2024-11-05T09:01:14+00:00\",\"dateModified\":\"2024-11-05T15:16:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/leadership-a-la-lincoln\\\/\"},\"wordCount\":1243,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/leadership-a-la-lincoln\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/image.png\",\"keywords\":[\"Apprendre\",\"D\u00e9cisions\",\"R\u00e9ussir personnellement\",\"R\u00e9ussir professionnellement\",\"Succ\u00e8s\"],\"articleSection\":[\"Blog\",\"R\u00e9ussir personnellement\",\"R\u00e9ussir professionnellement\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/leadership-a-la-lincoln\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/leadership-a-la-lincoln\\\/\",\"url\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/leadership-a-la-lincoln\\\/\",\"name\":\"Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger - Des options pour se d\u00e9velopper\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/leadership-a-la-lincoln\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/leadership-a-la-lincoln\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/image.png\",\"datePublished\":\"2024-11-05T09:01:14+00:00\",\"dateModified\":\"2024-11-05T15:16:42+00:00\",\"description\":\"Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/leadership-a-la-lincoln\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/leadership-a-la-lincoln\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/leadership-a-la-lincoln\\\/#primaryimage\",\"url\":\"https:\\\/\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/image.png\",\"contentUrl\":\"https:\\\/\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/image.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/leadership-a-la-lincoln\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/\",\"name\":\"Des options pour se d\u00e9velopper\",\"description\":\"Acc\u00e9l\u00e9rer les r\u00e9sultats sur vos projets importants\",\"publisher\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#organization\",\"name\":\"OptionsToGrow\",\"url\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo-web-1-e1597514267714.jpg?fit=96%2C65&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo-web-1-e1597514267714.jpg?fit=96%2C65&ssl=1\",\"width\":96,\"height\":65,\"caption\":\"OptionsToGrow\"},\"image\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Options-To-Grow-109035218181837\",\"https:\\\/\\\/x.com\\\/mr_otg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#\\\/schema\\\/person\\\/7dd82164ca7481a8c2d59969d4cef9eb\",\"name\":\"Dror Allouche\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g\",\"caption\":\"Dror Allouche\"},\"description\":\"Executive who ran a 9-figure business. I left corporate at the age of 46, financially independent. I write to share my learning on how to grow your life, your career, your money.\",\"sameAs\":[\"https:\\\/\\\/optionstogrow.com\\\/\",\"https:\\\/\\\/x.com\\\/mr_otg\"],\"url\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/author\\\/optionstogrow\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger - Des options pour se d\u00e9velopper","description":"Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/optionstogrow.com\/fr\/leadership-a-la-lincoln\/","og_locale":"fr_FR","og_type":"article","og_title":"Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger - Des options pour se d\u00e9velopper","og_description":"Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger","og_url":"https:\/\/optionstogrow.com\/fr\/leadership-a-la-lincoln\/","og_site_name":"Des options pour se d\u00e9velopper","article_publisher":"https:\/\/www.facebook.com\/Options-To-Grow-109035218181837","article_published_time":"2024-11-05T09:01:14+00:00","article_modified_time":"2024-11-05T15:16:42+00:00","og_image":[{"url":"https:\/\/optionstogrow.com\/wp-content\/uploads\/2024\/11\/image.png","type":"","width":"","height":""}],"author":"Dror Allouche","twitter_card":"summary_large_image","twitter_creator":"@mr_otg","twitter_site":"@mr_otg","twitter_misc":{"\u00c9crit par":"Dror Allouche","Dur\u00e9e de lecture estim\u00e9e":"6 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/optionstogrow.com\/fr\/leadership-a-la-lincoln\/#article","isPartOf":{"@id":"https:\/\/optionstogrow.com\/fr\/leadership-a-la-lincoln\/"},"author":{"name":"Dror Allouche","@id":"https:\/\/optionstogrow.com\/fr\/#\/schema\/person\/7dd82164ca7481a8c2d59969d4cef9eb"},"headline":"Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger","datePublished":"2024-11-05T09:01:14+00:00","dateModified":"2024-11-05T15:16:42+00:00","mainEntityOfPage":{"@id":"https:\/\/optionstogrow.com\/fr\/leadership-a-la-lincoln\/"},"wordCount":1243,"commentCount":0,"publisher":{"@id":"https:\/\/optionstogrow.com\/fr\/#organization"},"image":{"@id":"https:\/\/optionstogrow.com\/fr\/leadership-a-la-lincoln\/#primaryimage"},"thumbnailUrl":"https:\/\/optionstogrow.com\/wp-content\/uploads\/2024\/11\/image.png","keywords":["Apprendre","D\u00e9cisions","R\u00e9ussir personnellement","R\u00e9ussir professionnellement","Succ\u00e8s"],"articleSection":["Blog","R\u00e9ussir personnellement","R\u00e9ussir professionnellement"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/optionstogrow.com\/fr\/leadership-a-la-lincoln\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/optionstogrow.com\/fr\/leadership-a-la-lincoln\/","url":"https:\/\/optionstogrow.com\/fr\/leadership-a-la-lincoln\/","name":"Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger - Des options pour se d\u00e9velopper","isPartOf":{"@id":"https:\/\/optionstogrow.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/optionstogrow.com\/fr\/leadership-a-la-lincoln\/#primaryimage"},"image":{"@id":"https:\/\/optionstogrow.com\/fr\/leadership-a-la-lincoln\/#primaryimage"},"thumbnailUrl":"https:\/\/optionstogrow.com\/wp-content\/uploads\/2024\/11\/image.png","datePublished":"2024-11-05T09:01:14+00:00","dateModified":"2024-11-05T15:16:42+00:00","description":"Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger","breadcrumb":{"@id":"https:\/\/optionstogrow.com\/fr\/leadership-a-la-lincoln\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/optionstogrow.com\/fr\/leadership-a-la-lincoln\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/optionstogrow.com\/fr\/leadership-a-la-lincoln\/#primaryimage","url":"https:\/\/optionstogrow.com\/wp-content\/uploads\/2024\/11\/image.png","contentUrl":"https:\/\/optionstogrow.com\/wp-content\/uploads\/2024\/11\/image.png"},{"@type":"BreadcrumbList","@id":"https:\/\/optionstogrow.com\/fr\/leadership-a-la-lincoln\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/optionstogrow.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Leadership \u00e0 la Lincoln : 6 le\u00e7ons intemporelles pour inspirer et diriger"}]},{"@type":"WebSite","@id":"https:\/\/optionstogrow.com\/fr\/#website","url":"https:\/\/optionstogrow.com\/fr\/","name":"Des options pour se d\u00e9velopper","description":"Acc\u00e9l\u00e9rer les r\u00e9sultats sur vos projets importants","publisher":{"@id":"https:\/\/optionstogrow.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/optionstogrow.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/optionstogrow.com\/fr\/#organization","name":"OptionsToGrow","url":"https:\/\/optionstogrow.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/optionstogrow.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/07\/logo-web-1-e1597514267714.jpg?fit=96%2C65&ssl=1","contentUrl":"https:\/\/i1.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/07\/logo-web-1-e1597514267714.jpg?fit=96%2C65&ssl=1","width":96,"height":65,"caption":"OptionsToGrow"},"image":{"@id":"https:\/\/optionstogrow.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Options-To-Grow-109035218181837","https:\/\/x.com\/mr_otg"]},{"@type":"Person","@id":"https:\/\/optionstogrow.com\/fr\/#\/schema\/person\/7dd82164ca7481a8c2d59969d4cef9eb","name":"Dror Allouche","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g","caption":"Dror Allouche"},"description":"Executive who ran a 9-figure business. I left corporate at the age of 46, financially independent. I write to share my learning on how to grow your life, your career, your money.","sameAs":["https:\/\/optionstogrow.com\/","https:\/\/x.com\/mr_otg"],"url":"https:\/\/optionstogrow.com\/fr\/author\/optionstogrow\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcagkH-1Af","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/posts\/6091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/comments?post=6091"}],"version-history":[{"count":3,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/posts\/6091\/revisions"}],"predecessor-version":[{"id":6102,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/posts\/6091\/revisions\/6102"}],"wp:attachment":[{"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/media?parent=6091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/categories?post=6091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/tags?post=6091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}