{"id":5985,"date":"2020-09-30T03:22:10","date_gmt":"2020-09-30T03:22:10","guid":{"rendered":"https:\/\/optionstogrow.com\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\/"},"modified":"2025-08-11T12:17:18","modified_gmt":"2025-08-11T12:17:18","slug":"au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme","status":"publish","type":"post","link":"https:\/\/optionstogrow.com\/fr\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\/","title":{"rendered":"Au-del\u00e0 de l&rsquo;Urgent et de l&rsquo;Important : Les habitudes \u00ab Non urgentes mais importantes \u00bb qui m\u00e8nent au succ\u00e8s \u00e0 long terme"},"content":{"rendered":"\n<p>J&rsquo;entends souvent dire : <\/p>\n\n<p> \u00ab\u00a0Les vendeurs sont pr\u00eats \u00e0 tout pour gagner de l&rsquo;argent. <\/p>\n\n<p>C&rsquo;est logique. Il n&rsquo;y a pas de meilleur rapport entre l&rsquo;effort et le gain que dans la vente. <\/p>\n\n<p>Je ne suis pas d&rsquo;accord.<\/p>\n\n<p>M\u00eame les vendeurs ne font pas tout et souvent ne font pas des choses \u00e9videntes pour augmenter leur potentiel de gain. Le probl\u00e8me vient surtout de notre capacit\u00e9 \u00e0 distinguer les activit\u00e9s \u00ab\u00a0non urgentes mais importantes\u00a0\u00bb et \u00e0 agir en cons\u00e9quence.   <a href=\"https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/\" target=\"_blank\" rel=\"noreferrer noopener\">( Voir Mettre les choses au premier plan)<\/a><br\/><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/09\/This-5-Minute-Habit-Generated-Millions-1.jpg?resize=819%2C1024&#038;ssl=1\" alt=\"Au-del&#xE0; de l'Urgent et de l'Important : Les habitudes &#xAB; Non urgentes mais importantes &#xBB; qui m&#xE8;nent au succ&#xE8;s &#xE0; long terme\" class=\"wp-image-6711\" style=\"width:450px\" srcset=\"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/09\/This-5-Minute-Habit-Generated-Millions-1.jpg?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/09\/This-5-Minute-Habit-Generated-Millions-1.jpg?resize=240%2C300&amp;ssl=1 240w, https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/09\/This-5-Minute-Habit-Generated-Millions-1.jpg?resize=768%2C960&amp;ssl=1 768w, https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/09\/This-5-Minute-Habit-Generated-Millions-1.jpg?resize=1229%2C1536&amp;ssl=1 1229w, https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/09\/This-5-Minute-Habit-Generated-Millions-1.jpg?w=1600&amp;ssl=1 1600w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/figure>\n<\/div>\n<h2 class=\"wp-block-heading\">Les habitudes \u00ab\u00a0non urgentes mais importantes\u00a0\u00bb qui m&rsquo;ont aid\u00e9 tout au long de ma carri\u00e8re.<\/h2>\n\n<p>J&rsquo;ai commenc\u00e9 ma carri\u00e8re comme vendeur et j&rsquo;<a href=\"https:\/\/optionstogrow.com\/fr\/jai-ete-promu-8-fois-et-ai-multiplie-mon-salaire-par-10-dans-ma-carriere-de-salarie-mes-4-etapes-de-decision-face-a-une-opportunite-de-carriere\/\">ai gravi les \u00e9che<\/a> lons jusqu&rsquo;au comit\u00e9 de direction d&rsquo;une entreprise de 5 000 personnes. Mon premier travail consistait \u00e0 trouver de nouveaux clients. <\/p>\n\n<p>Comme tout dans ma vie, je me plonge dans l&rsquo;exp\u00e9rience des autres en <a href=\"https:\/\/optionstogrow.com\/fr\/livres-que-jai-lus\/\">lisant des livres.<\/a> Apr\u00e8s chaque r\u00e9union, je r\u00e9fl\u00e9chis \u00e0 ce que je pourrais am\u00e9liorer.  <\/p>\n\n<p>Au bout de six mois, j&rsquo;ai commenc\u00e9 \u00e0 obtenir les meilleurs r\u00e9sultats parmi une douzaine de vendeurs de ma cat\u00e9gorie.<\/p>\n\n<p>Plus tard, j&rsquo;ai \u00e9t\u00e9 promu \u00e0 un poste ax\u00e9 sur l&rsquo;\u00e9tablissement de relations avec les clients existants. \u00c0 24 ans, j&rsquo;\u00e9tais le plus jeune parmi 100 vendeurs exp\u00e9riment\u00e9s, et pourtant, en six mois, j&rsquo;ai obtenu les meilleurs r\u00e9sultats. <\/p>\n\n<p>Ma m\u00e9thodologie pouvait \u00eatre reproduite. Les vendeurs ont commenc\u00e9 \u00e0 m&rsquo;approcher et m&rsquo;ont demand\u00e9 :   <\/p>\n\n<p>\u00ab\u00a0Quel est ton secret ?\u00a0\u00bb<\/p>\n\n<p><a href=\"https:\/\/winning-writer-6789.ck.page\/2063ed76c8\" target=\"_blank\" rel=\"noreferrer noopener\">Consultez mon guide de ressources : Les 11 livres qui ont le plus influenc\u00e9 ma carri\u00e8re. (Y compris mon pr\u00e9f\u00e9r\u00e9 toutes cat\u00e9gories confondues)<\/a><\/p>\n\n<h2 class=\"wp-block-heading\">Au-del\u00e0 de l&rsquo;urgent et de l&rsquo;important : le pouvoir de quelques mots personnels \u00e9crits<\/h2>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"773\" src=\"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/09\/image-2.png?resize=768%2C773&#038;ssl=1\" alt=\"Au-del&#xE0; de l'Urgent et de l'Important : Les habitudes &#xAB; Non urgentes mais importantes &#xBB; qui m&#xE8;nent au succ&#xE8;s &#xE0; long terme\" class=\"wp-image-5976\" style=\"width:350px\" srcset=\"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/09\/image-2.png?w=768&amp;ssl=1 768w, https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/09\/image-2.png?resize=298%2C300&amp;ssl=1 298w, https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/09\/image-2.png?resize=150%2C150&amp;ssl=1 150w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\"><sup>Au-del\u00e0 de l&rsquo;Urgent et de l&rsquo;Important : Les habitudes \u00ab Non urgentes mais importantes \u00bb qui m\u00e8nent au succ\u00e8s \u00e0 long terme<\/sup><\/figcaption><\/figure>\n<\/div>\n<p>L&rsquo;une des choses que je faisais le plus souvent \u00e9tait d&rsquo;\u00e9crire quelques mots personnels \u00e0 l&rsquo;intention de mes clients.  <br\/>Je l&rsquo;utilise encore dans de nombreuses situations. Les choses qui fonctionnent sont souvent d&rsquo;une simplicit\u00e9 trompeuse<a href=\"https:\/\/optionstogrow.com\/can-you-afford-not-to-be-rich\/\" target=\"_blank\" rel=\"noreferrer noopener\">(voir ma strat\u00e9gie d&rsquo;investissement<\/a>). <\/p>\n\n<p>Apr\u00e8s chaque visite de vente, o\u00f9 le client \u00e9tait humainement bon avec moi &#8211; quel que soit le r\u00e9sultat de la vente &#8211; j&rsquo;\u00e9crivais une petite carte pour remercier cette personne pour son accueil chaleureux.<\/p>\n\n<p>Rien de particulier. Trois phrases avec un peu de personnalisation. Chaque carte m&rsquo;a pris 5 minutes.    <\/p>\n\n<p>J&rsquo;ai gard\u00e9 cette habitude d&rsquo;\u00e9crire \u00e0 mes coll\u00e8gues, patrons, employ\u00e9s, partenaires, \u00ab\u00a0quelques mots personnels\u00a0\u00bb pour les remercier de quelque chose de sp\u00e9cial qui m&rsquo;avait touch\u00e9.<\/p>\n\n<p>Je ne peux pas compter le nombre de relations plus profondes et les millions d&rsquo;euros de business que j&rsquo;ai construits gr\u00e2ce \u00e0 cette simple habitude.<\/p>\n\n<h2 class=\"wp-block-heading\">Le comment ? <\/h2>\n\n<p>Je l&rsquo;ai partag\u00e9 avec mes coll\u00e8gues et j&rsquo;ai m\u00eame fourni le mode d&#8217;emploi :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Quel type de carte ?<\/li>\n\n\n\n<li>Un exemple de carte \u00e9crite.<\/li>\n\n\n\n<li>Comment je regroupais mon travail pour \u00eatre plus productif.<\/li>\n<\/ul>\n\n<p>Malgr\u00e9 cela, je ne me souviens pas d&rsquo;un coll\u00e8gue commercial qui l&rsquo;ait appliqu\u00e9 avec discipline sur une longue p\u00e9riode. Certains n&rsquo;ont pas commenc\u00e9, d&rsquo;autres ont arr\u00eat\u00e9, m\u00eame s&rsquo;ils ont commenc\u00e9 \u00e0 augmenter leurs ratios de vente. <\/p>\n\n<h2 class=\"wp-block-heading\">Pourquoi ne l&rsquo;ont-ils pas fait ?<\/h2>\n\n<p>Pas parce qu&rsquo;ils n&rsquo;y croyaient pas. <\/p>\n\n<p>La raison principale est qu&rsquo;ils mouraient, comme la plupart d&rsquo;entre nous, sous le poids de leurs t\u00e2ches \u00ab\u00a0urgentes et importantes\u00a0\u00bb. Ils n&rsquo;arrivaient pas \u00e0 faire de la place pour leurs activit\u00e9s \u00ab\u00a0non urgentes mais importantes\u00a0\u00bb, telles que l&rsquo;envoi de cartes \u00e0 leurs prospects les plus fid\u00e8les. <\/p>\n\n<p>Et comme souvent, les habitudes \u00ab\u00a0non urgentes mais importantes\u00a0\u00bb sont simples, semblent futiles, mais sont cruciales pour notre r\u00e9ussite \u00e0 long terme.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Exercices de respiration, <\/li>\n\n\n\n<li><a href=\"https:\/\/optionstogrow.com\/fr\/vous-voulez-prendre-de-meilleures-decisions-et-si-la-reponse-netait-pas-une-nouvelle-application-mais-une-bonne-nuit-de-sommeil\/\">Dormir <\/a>une heure plus t\u00f4t, <\/li>\n\n\n\n<li>Promenade quotidienne, lire 15 minutes par jour, <\/li>\n\n\n\n<li>\u00c9crire quotidiennement dans notre <a href=\"https:\/\/optionstogrow.com\/fr\/vous-voulez-commencer-a-tenir-un-journal-mais-vous-ne-savez-pas-par-ou-commencer-11-idees-qui-pourraient-vous-aider-tirees-de-mes-7-dernieres-annees-decriture-quotidienne\/\">journal<\/a><\/li>\n\n\n\n<li>Comprendre d&rsquo;abord avant d&rsquo;\u00eatre compris&#8230;<\/li>\n<\/ul>\n\n<p>Ces habitudes sont simples et donnent de grands r\u00e9sultats au fil du temps.  <\/p>\n\n<p>Le d\u00e9fi ? Nous devons les mettre en \u0153uvre de mani\u00e8re proactive. <\/p>\n\n<h2 class=\"wp-block-heading\">L&rsquo;habitude des 20 % : Un syst\u00e8me simple pour obtenir 80 % de vos r\u00e9sultats<\/h2>\n\n<p>Passer du savoir \u00e0 l&rsquo;action est la partie la plus difficile. Le secret n&rsquo;est pas de trouver plus de temps, mais de cr\u00e9er un syst\u00e8me pour l&rsquo;habitude qui compte le plus. <\/p>\n\n<h3 class=\"wp-block-heading\">Voici un processus simple, en trois \u00e9tapes, pour y parvenir :<\/h3>\n\n<ul class=\"wp-block-list\">\n<li><strong>1. Isolez votre habitude des 5 minutes.<\/strong> Quelle est la petite action \u00ab\u00a0non urgente\u00a0\u00bb qui pourrait avoir le plus grand impact sur vos objectifs \u00e0 long terme ? N&rsquo;y r\u00e9fl\u00e9chissez pas trop. Il peut s&rsquo;agir d&rsquo;\u00e9crire un mot de remerciement. Il pourrait s&rsquo;agir de passer 5 minutes \u00e0 planifier votre prochaine journ\u00e9e avant d&rsquo;\u00e9teindre votre ordinateur. Il peut s&rsquo;agir d&rsquo;envoyer un article \u00e0 un client important pour lui montrer que vous pensez \u00e0 lui. Choisissez-en une. Simplifiez-vous la vie.      <\/li>\n\n\n\n<li><strong>2. Inscrivez-le dans votre calendrier.<\/strong>  Une habitude sans horaire n&rsquo;est qu&rsquo;un souhait. Vous devez lui donner un temps et un lieu pour vivre. \n<ul class=\"wp-block-list\">\n<li><strong>Option A : Empilement d&rsquo;habitudes.<\/strong>  Reliez votre nouvelle habitude \u00e0 une habitude existante. \u00ab\u00a0Apr\u00e8s avoir bu mon caf\u00e9 du matin, j&rsquo;\u00e9crirai dans mon journal pendant 5 minutes. <\/li>\n\n\n\n<li><strong>Option B : Blocage du temps.<\/strong>  Planifiez-le comme une r\u00e9union importante. \u00ab\u00a0Chaque vendredi \u00e0 16 heures, je consacrerai 15 minutes \u00e0 la r\u00e9daction de mes cartes de remerciement hebdomadaires. Cela rend l&rsquo;exercice non n\u00e9gociable.  <\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>3. Suivez vos victoires.<\/strong>  L&rsquo;\u00e9lan est votre meilleur ami. Procurez-vous un calendrier mural simple et dessinez un grand \u00ab\u00a0X\u00a0\u00bb sur chaque jour o\u00f9 vous terminez votre habitude. Votre seul objectif est de ne pas briser la cha\u00eene. Le fait de voir la cha\u00eene de \u00ab\u00a0X\u00a0\u00bb s&rsquo;allonger cr\u00e9e une puissante boucle de r\u00e9troaction visuelle qui vous motive \u00e0 continuer.   <\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Une derni\u00e8re r\u00e9flexion<\/h2>\n\n<p>Maintenant, prenez un moment et posez-vous cette question de coaching :<\/p>\n\n<p>Si vous vous consacrez \u00e0 cette petite habitude pendant les 90 prochains jours, quel r\u00e9sultat cl\u00e9 pourrait \u00eatre compl\u00e8tement transform\u00e9 ?<\/p>\n\n<p>\u00c0 bient\u00f4t.<br\/>Dror<\/p>\n\n<p>PS : D\u00e8s que vous \u00eates pr\u00eat, voici 2 autres fa\u00e7ons dont je peux vous aider \u00e0 acc\u00e9l\u00e9rer vos projets importants <strong>gr\u00e2ce au coaching :<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Vous<strong>\u00eates ambitieux<\/strong>: vous avez d\u00e9j\u00e0 beaucoup accompli. Et vous avez l&rsquo;intention de continuer. Mais cette fois, vous voulez le faire en profitant des choses importantes de votre vie. <a href=\"https:\/\/optionstogrow.com\/fr\/blog\/\">Curieux? Cliquez ici<\/a>.<\/li>\n\n\n\n<li>Vous <strong>dirigez une \u00e9quipe<\/strong>: vous savez qu&rsquo;une petite am\u00e9lioration de votre leadership peut avoir un impact \u00e9norme sur les r\u00e9sultats de l&rsquo;\u00e9quipe et, par cons\u00e9quent, sur votre carri\u00e8re. J&rsquo;ai \u00e9t\u00e9 form\u00e9 et certifi\u00e9 par le premier coach ex\u00e9cutif au monde, Marshall Goldsmith. Je vous accompagne dans votre projet et garantis le r\u00e9sultat. Vous ne me payez que si vous r\u00e9ussissez. Vous souhaitez en savoir plus ? <a href=\"https:\/\/optionstogrow.com\/?page_id=3412\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/optionstogrow.com\/?page_id=3412\">Contactez-moi et d\u00e9couvrons si nous pouvons travailler ensemble.<\/a><\/li>\n<\/ul>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>J&rsquo;ai souvent entendu : \u00a0\u00bb oui, mais les vendeurs sont pr\u00eats \u00e0 tout pour gagner de l&rsquo;argent \u00ab\u00a0. Et je peux comprendre d&rsquo;o\u00f9 cela vient. Il n&rsquo;y a pas de meilleur rapport entre l&rsquo;effort et le gain que dans la vente.<br \/>\nMais je ne suis pas d&rsquo;accord ; m\u00eame les vendeurs ne font pas tout et souvent ne font pas des choses \u00e9videntes pour augmenter leur potentiel de gain. Le probl\u00e8me vient surtout de notre capacit\u00e9 \u00e0 distinguer les activit\u00e9s \u00ab\u00a0non urgentes mais importantes\u00a0\u00bb et \u00e0 agir en cons\u00e9quence.     <\/p>\n","protected":false},"author":2,"featured_media":6712,"comment_status":"open","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_wp_convertkit_post_meta":{"form":"-1","landing_page":"","tag":"0","restrict_content":"0"},"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[85,84,79],"tags":[82,104],"class_list":{"0":"post-5985","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-blog-fr","8":"category-reussir-personnellement","9":"category-reussir-professionnellement","10":"tag-creativite","11":"tag-productivite","12":"entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Au-del\u00e0 de l&#039;Urgent et de l&#039;Important : Les habitudes \u00ab Non urgentes mais importantes \u00bb qui m\u00e8nent au succ\u00e8s \u00e0 long terme - Des options pour se d\u00e9velopper<\/title>\n<meta name=\"description\" content=\"Comment puis-je mieux r\u00e9ussir dans mes affaires et dans ma vie ? Les t\u00e2ches &quot;non urgentes mais importantes&quot; sont simples, semblent futiles au quotidien, mais sont cruciales pour notre r\u00e9ussite \u00e0 long terme. L&#039;une des comp\u00e9tences essentielles pour r\u00e9ussir est...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/optionstogrow.com\/fr\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Au-del\u00e0 de l&#039;Urgent et de l&#039;Important : Les habitudes \u00ab Non urgentes mais importantes \u00bb qui m\u00e8nent au succ\u00e8s \u00e0 long terme - Des options pour se d\u00e9velopper\" \/>\n<meta property=\"og:description\" content=\"Comment puis-je mieux r\u00e9ussir dans mes affaires et dans ma vie ? Les t\u00e2ches &quot;non urgentes mais importantes&quot; sont simples, semblent futiles au quotidien, mais sont cruciales pour notre r\u00e9ussite \u00e0 long terme. L&#039;une des comp\u00e9tences essentielles pour r\u00e9ussir est...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/optionstogrow.com\/fr\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\/\" \/>\n<meta property=\"og:site_name\" content=\"Des options pour se d\u00e9velopper\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Options-To-Grow-109035218181837\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-30T03:22:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-11T12:17:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/09\/This-5-Minute-Habit-Generated-Millions-1.jpg?fit=1600%2C2000&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dror Allouche\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mr_otg\" \/>\n<meta name=\"twitter:site\" content=\"@mr_otg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dror Allouche\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\\\/\"},\"author\":{\"name\":\"Dror Allouche\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#\\\/schema\\\/person\\\/7dd82164ca7481a8c2d59969d4cef9eb\"},\"headline\":\"Au-del\u00e0 de l&rsquo;Urgent et de l&rsquo;Important : Les habitudes \u00ab Non urgentes mais importantes \u00bb qui m\u00e8nent au succ\u00e8s \u00e0 long terme\",\"datePublished\":\"2020-09-30T03:22:10+00:00\",\"dateModified\":\"2025-08-11T12:17:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\\\/\"},\"wordCount\":1189,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/This-5-Minute-Habit-Generated-Millions-1.jpg?fit=1600%2C2000&ssl=1\",\"keywords\":[\"Cr\u00e9ativit\u00e9\",\"Productivit\u00e9\"],\"articleSection\":[\"Blog\",\"R\u00e9ussir personnellement\",\"R\u00e9ussir professionnellement\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\\\/\",\"url\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\\\/\",\"name\":\"Au-del\u00e0 de l'Urgent et de l'Important : Les habitudes \u00ab Non urgentes mais importantes \u00bb qui m\u00e8nent au succ\u00e8s \u00e0 long terme - Des options pour se d\u00e9velopper\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/This-5-Minute-Habit-Generated-Millions-1.jpg?fit=1600%2C2000&ssl=1\",\"datePublished\":\"2020-09-30T03:22:10+00:00\",\"dateModified\":\"2025-08-11T12:17:18+00:00\",\"description\":\"Comment puis-je mieux r\u00e9ussir dans mes affaires et dans ma vie ? Les t\u00e2ches \\\"non urgentes mais importantes\\\" sont simples, semblent futiles au quotidien, mais sont cruciales pour notre r\u00e9ussite \u00e0 long terme. L'une des comp\u00e9tences essentielles pour r\u00e9ussir est...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/This-5-Minute-Habit-Generated-Millions-1.jpg?fit=1600%2C2000&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/This-5-Minute-Habit-Generated-Millions-1.jpg?fit=1600%2C2000&ssl=1\",\"width\":1600,\"height\":2000,\"caption\":\"Beyond the Urgent and Important: The 'Non-Urgent but Important' Habits That Drive Long-Term Success\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Au-del\u00e0 de l&rsquo;Urgent et de l&rsquo;Important : Les habitudes \u00ab Non urgentes mais importantes \u00bb qui m\u00e8nent au succ\u00e8s \u00e0 long terme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/\",\"name\":\"Des options pour se d\u00e9velopper\",\"description\":\"Acc\u00e9l\u00e9rer les r\u00e9sultats sur vos projets importants\",\"publisher\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#organization\",\"name\":\"OptionsToGrow\",\"url\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo-web-1-e1597514267714.jpg?fit=96%2C65&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo-web-1-e1597514267714.jpg?fit=96%2C65&ssl=1\",\"width\":96,\"height\":65,\"caption\":\"OptionsToGrow\"},\"image\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Options-To-Grow-109035218181837\",\"https:\\\/\\\/x.com\\\/mr_otg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#\\\/schema\\\/person\\\/7dd82164ca7481a8c2d59969d4cef9eb\",\"name\":\"Dror Allouche\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g\",\"caption\":\"Dror Allouche\"},\"description\":\"Executive who ran a 9-figure business. I left corporate at the age of 46, financially independent. I write to share my learning on how to grow your life, your career, your money.\",\"sameAs\":[\"https:\\\/\\\/optionstogrow.com\\\/\",\"https:\\\/\\\/x.com\\\/mr_otg\"],\"url\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/author\\\/optionstogrow\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Au-del\u00e0 de l'Urgent et de l'Important : Les habitudes \u00ab Non urgentes mais importantes \u00bb qui m\u00e8nent au succ\u00e8s \u00e0 long terme - Des options pour se d\u00e9velopper","description":"Comment puis-je mieux r\u00e9ussir dans mes affaires et dans ma vie ? Les t\u00e2ches \"non urgentes mais importantes\" sont simples, semblent futiles au quotidien, mais sont cruciales pour notre r\u00e9ussite \u00e0 long terme. L'une des comp\u00e9tences essentielles pour r\u00e9ussir est...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/optionstogrow.com\/fr\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\/","og_locale":"fr_FR","og_type":"article","og_title":"Au-del\u00e0 de l'Urgent et de l'Important : Les habitudes \u00ab Non urgentes mais importantes \u00bb qui m\u00e8nent au succ\u00e8s \u00e0 long terme - Des options pour se d\u00e9velopper","og_description":"Comment puis-je mieux r\u00e9ussir dans mes affaires et dans ma vie ? Les t\u00e2ches \"non urgentes mais importantes\" sont simples, semblent futiles au quotidien, mais sont cruciales pour notre r\u00e9ussite \u00e0 long terme. L'une des comp\u00e9tences essentielles pour r\u00e9ussir est...","og_url":"https:\/\/optionstogrow.com\/fr\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\/","og_site_name":"Des options pour se d\u00e9velopper","article_publisher":"https:\/\/www.facebook.com\/Options-To-Grow-109035218181837","article_published_time":"2020-09-30T03:22:10+00:00","article_modified_time":"2025-08-11T12:17:18+00:00","og_image":[{"width":1600,"height":2000,"url":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/09\/This-5-Minute-Habit-Generated-Millions-1.jpg?fit=1600%2C2000&ssl=1","type":"image\/jpeg"}],"author":"Dror Allouche","twitter_card":"summary_large_image","twitter_creator":"@mr_otg","twitter_site":"@mr_otg","twitter_misc":{"\u00c9crit par":"Dror Allouche","Dur\u00e9e de lecture estim\u00e9e":"4 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/optionstogrow.com\/fr\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\/#article","isPartOf":{"@id":"https:\/\/optionstogrow.com\/fr\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\/"},"author":{"name":"Dror Allouche","@id":"https:\/\/optionstogrow.com\/fr\/#\/schema\/person\/7dd82164ca7481a8c2d59969d4cef9eb"},"headline":"Au-del\u00e0 de l&rsquo;Urgent et de l&rsquo;Important : Les habitudes \u00ab Non urgentes mais importantes \u00bb qui m\u00e8nent au succ\u00e8s \u00e0 long terme","datePublished":"2020-09-30T03:22:10+00:00","dateModified":"2025-08-11T12:17:18+00:00","mainEntityOfPage":{"@id":"https:\/\/optionstogrow.com\/fr\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\/"},"wordCount":1189,"commentCount":0,"publisher":{"@id":"https:\/\/optionstogrow.com\/fr\/#organization"},"image":{"@id":"https:\/\/optionstogrow.com\/fr\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/09\/This-5-Minute-Habit-Generated-Millions-1.jpg?fit=1600%2C2000&ssl=1","keywords":["Cr\u00e9ativit\u00e9","Productivit\u00e9"],"articleSection":["Blog","R\u00e9ussir personnellement","R\u00e9ussir professionnellement"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/optionstogrow.com\/fr\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/optionstogrow.com\/fr\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\/","url":"https:\/\/optionstogrow.com\/fr\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\/","name":"Au-del\u00e0 de l'Urgent et de l'Important : Les habitudes \u00ab Non urgentes mais importantes \u00bb qui m\u00e8nent au succ\u00e8s \u00e0 long terme - Des options pour se d\u00e9velopper","isPartOf":{"@id":"https:\/\/optionstogrow.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/optionstogrow.com\/fr\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\/#primaryimage"},"image":{"@id":"https:\/\/optionstogrow.com\/fr\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/09\/This-5-Minute-Habit-Generated-Millions-1.jpg?fit=1600%2C2000&ssl=1","datePublished":"2020-09-30T03:22:10+00:00","dateModified":"2025-08-11T12:17:18+00:00","description":"Comment puis-je mieux r\u00e9ussir dans mes affaires et dans ma vie ? Les t\u00e2ches \"non urgentes mais importantes\" sont simples, semblent futiles au quotidien, mais sont cruciales pour notre r\u00e9ussite \u00e0 long terme. L'une des comp\u00e9tences essentielles pour r\u00e9ussir est...","breadcrumb":{"@id":"https:\/\/optionstogrow.com\/fr\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/optionstogrow.com\/fr\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/optionstogrow.com\/fr\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\/#primaryimage","url":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/09\/This-5-Minute-Habit-Generated-Millions-1.jpg?fit=1600%2C2000&ssl=1","contentUrl":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/09\/This-5-Minute-Habit-Generated-Millions-1.jpg?fit=1600%2C2000&ssl=1","width":1600,"height":2000,"caption":"Beyond the Urgent and Important: The 'Non-Urgent but Important' Habits That Drive Long-Term Success"},{"@type":"BreadcrumbList","@id":"https:\/\/optionstogrow.com\/fr\/au-dela-de-lurgent-et-de-limportant-les-habitudes-non-urgentes-mais-importantes-qui-menent-au-succes-a-long-terme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/optionstogrow.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Au-del\u00e0 de l&rsquo;Urgent et de l&rsquo;Important : Les habitudes \u00ab Non urgentes mais importantes \u00bb qui m\u00e8nent au succ\u00e8s \u00e0 long terme"}]},{"@type":"WebSite","@id":"https:\/\/optionstogrow.com\/fr\/#website","url":"https:\/\/optionstogrow.com\/fr\/","name":"Des options pour se d\u00e9velopper","description":"Acc\u00e9l\u00e9rer les r\u00e9sultats sur vos projets importants","publisher":{"@id":"https:\/\/optionstogrow.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/optionstogrow.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/optionstogrow.com\/fr\/#organization","name":"OptionsToGrow","url":"https:\/\/optionstogrow.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/optionstogrow.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/07\/logo-web-1-e1597514267714.jpg?fit=96%2C65&ssl=1","contentUrl":"https:\/\/i1.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/07\/logo-web-1-e1597514267714.jpg?fit=96%2C65&ssl=1","width":96,"height":65,"caption":"OptionsToGrow"},"image":{"@id":"https:\/\/optionstogrow.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Options-To-Grow-109035218181837","https:\/\/x.com\/mr_otg"]},{"@type":"Person","@id":"https:\/\/optionstogrow.com\/fr\/#\/schema\/person\/7dd82164ca7481a8c2d59969d4cef9eb","name":"Dror Allouche","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g","caption":"Dror Allouche"},"description":"Executive who ran a 9-figure business. I left corporate at the age of 46, financially independent. I write to share my learning on how to grow your life, your career, your money.","sameAs":["https:\/\/optionstogrow.com\/","https:\/\/x.com\/mr_otg"],"url":"https:\/\/optionstogrow.com\/fr\/author\/optionstogrow\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/09\/This-5-Minute-Habit-Generated-Millions-1.jpg?fit=1600%2C2000&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcagkH-1yx","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/posts\/5985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/comments?post=5985"}],"version-history":[{"count":4,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/posts\/5985\/revisions"}],"predecessor-version":[{"id":6716,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/posts\/5985\/revisions\/6716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/media\/6712"}],"wp:attachment":[{"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/media?parent=5985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/categories?post=5985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/tags?post=5985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}