{"id":2409,"date":"2022-03-12T08:19:29","date_gmt":"2022-03-12T08:19:29","guid":{"rendered":"https:\/\/optionstogrow.com\/?p=2409"},"modified":"2022-03-12T13:48:31","modified_gmt":"2022-03-12T13:48:31","slug":"comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples","status":"publish","type":"post","link":"https:\/\/optionstogrow.com\/fr\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\/","title":{"rendered":"Comment passer de la stagnation \u00e0 la cr\u00e9ation ? Essayez ces 2 questions toutes simples."},"content":{"rendered":"\n<p>La vie est dynamique. Vous pouvez \u00eatre dans une bonne phase et d&rsquo;un coup, sans m\u00eame vous en rendre compte, vous entrez dans une phase de stagnation.<\/p>\n\n\n\n<p>N&rsquo;y restez pas. Pourquoi?<\/p>\n\n\n\n<p>Les peurs viennent de mauvaises pens\u00e9es. Et elles se d\u00e9veloppent dans le terreau de l&rsquo;inaction. De l&rsquo;eau qui stagne, une \u00e9conomie stagnante, tout cela ne pr\u00e9dit rien de bon.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" src=\"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2022\/03\/pexels-andrew-neel-5255996.jpg?resize=640%2C426&#038;ssl=1\" alt=\"\" class=\"wp-image-2410\" srcset=\"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2022\/03\/pexels-andrew-neel-5255996.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2022\/03\/pexels-andrew-neel-5255996.jpg?resize=300%2C200&amp;ssl=1 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption><sup>Comment passer de la stagnation \u00e0 la cr\u00e9ation ? Essayez ces 2 questions toutes simples.<br>Photo d&rsquo;<strong><a href=\"https:\/\/www.pexels.com\/@andrew?utm_content=attributionCopyText&amp;utm_medium=referral&amp;utm_source=pexels\">Andrew Neel<\/a><\/strong>&nbsp;de <strong><a href=\"https:\/\/www.pexels.com\/photo\/man-in-gray-long-sleeve-shirt-sitting-on-brown-wooden-chair-5255996\/?utm_content=attributionCopyText&amp;utm_medium=referral&amp;utm_source=pexels\">Pexels<\/a><\/strong><\/sup><\/figcaption><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Le passage \u00e0 l&rsquo;action. <\/h2>\n\n\n\n<p>De l&rsquo;autre c\u00f4t\u00e9, quand vous entrez dans l&rsquo;action. Vous commencez un processus du futur, des possibles.<\/p>\n\n\n\n<p>L&rsquo;action produit de nouvelles options, de nouveaux espoirs.<\/p>\n\n\n\n<p>Rappelez-vous la derni\u00e8re fois que vous avez parl\u00e9 \u00e0 quelqu&rsquo;un d&rsquo;enthousiaste. \u00c9tait-il dans un \u00e9tat de stagnation ou de cr\u00e9ation? \u00c9tait-il \u00e0 l&rsquo;arr\u00eat ou en action?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-2-questions-pour-vous-assurer-de-rester-dans-un-etat-de-creation-intentionnelle\">2 questions pour vous assurer de rester dans un \u00e9tat de cr\u00e9ation intentionnelle&nbsp;<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Qu&rsquo;est-ce que je souhaite r\u00e9aliser ?<\/li><li>Quelle est la prochaine action ?<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">La simplicit\u00e9 : une cl\u00e9 de l&rsquo;action. <\/h2>\n\n\n\n<p>Bien s\u00fbr, vous pouvez utiliser des outils plus sophistiqu\u00e9s. Mais la simplicit\u00e9 est une cl\u00e9 de l&rsquo;action. Gardez les choses simples. Quand vous \u00eates dans une mauvaise passe (stagnation). Demandez-vous \u00ab qu&rsquo;est-ce que je souhaite faire? \u00bb&nbsp;<\/p>\n\n\n\n<p>Cette question vous assure de grimper sur le bon mur. \u00c7a serait dommage de se rendre compte qu&rsquo;on s&rsquo;est tromp\u00e9 une fois arriv\u00e9 en haut.\ud83d\ude00<\/p>\n\n\n\n<p>Maitenant que vous \u00eates dans la bonne direction, il ne vous reste plus qu&rsquo;\u00e0 vous demander \u00ab\u00a0quelle est la prochaine action?\u00a0\u00bb. Si vous avez beaucoup d&rsquo;\u00e9nergie, vous pouvez vous lancer dans une grande t\u00e2che. Sinon commencez petit.<\/p>\n\n\n\n<p>L&rsquo;action, m\u00eame petite, a le pouvoir de changer votre \u00e9tat d&rsquo;esprit. Alors, profitez-en et mettez vous en action.<\/p>\n\n\n\n<p>\u00c0 vous de jouer.<\/p>\n\n\n\n<p>Articles li\u00e9s : <\/p>\n\n\n\n<p><a href=\"https:\/\/optionstogrow.com\/fr\/vous-cherchez-a-sortir-rapidement-dune-baisse-de-moral-voici-une-idee-et-4-facons-de-lappliquer-aujourdhui\/\">Vous cherchez \u00e0 sortir rapidement d\u2019une baisse de moral? Voici une id\u00e9e et 4 fa\u00e7ons de l\u2019appliquer d\u00e8s aujourd\u2019hui.<\/a><br><a href=\"https:\/\/optionstogrow.com\/fr\/comment-construire-son-projet-de-vie\/\">Comment construire son projet de vie ?<\/a><br><a href=\"https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/\">\u00ab&nbsp;Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu\u2019ils entreprennent&nbsp;\u00bb. Comment cela a transform\u00e9 ma vie et pourquoi cela peut changer la v\u00f4tre.<\/a><br><a href=\"https:\/\/optionstogrow.com\/fr\/mon-travail-me-prend-tout-mon-temps-comment-reprendre-le-controle-de-ma-vie\/\">Mon travail me prend tout mon temps. Comment reprendre le contr\u00f4le de ma vie ?<\/a><br><a href=\"https:\/\/optionstogrow.com\/fr\/vous-voulez-penser-librement-voici-4-idees-pour-sextraire-du-culte-de-la-validation-externe-et-developpez-son-systeme-de-validation-interne\/\">Vous voulez penser librement?&nbsp;Voici 4 id\u00e9es pour s\u2019extraire du culte de la validation externe et d\u00e9veloppez son syst\u00e8me de validation interne?&nbsp;<\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c7a nous arrive tous. Un moment de stagnation. Le tout est de ne pas y rester. Ces deux questions sont l\u00e0 pour vous aider. <\/p>\n","protected":false},"author":2,"featured_media":2410,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_wp_convertkit_post_meta":{"form":"2577560","landing_page":"","tag":"2605809"},"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[77,84],"tags":[81,82,89,105],"class_list":{"0":"post-2409","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-reflexion-courte","8":"category-reussir-personnellement","9":"tag-clarte","10":"tag-creativite","11":"tag-decisions-fr","12":"tag-responsabilite","13":"entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment passer de la stagnation \u00e0 la cr\u00e9ation ? Essayez ces 2 questions toutes simples. - Des options pour se d\u00e9velopper<\/title>\n<meta name=\"description\" content=\"\u00c7a nous arrive tous. Un moment de stagnation. Le tout est de ne pas y rester. Ces deux questions sont l\u00e0 pour vous aider.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/optionstogrow.com\/fr\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment passer de la stagnation \u00e0 la cr\u00e9ation ? Essayez ces 2 questions toutes simples. - Des options pour se d\u00e9velopper\" \/>\n<meta property=\"og:description\" content=\"\u00c7a nous arrive tous. Un moment de stagnation. Le tout est de ne pas y rester. Ces deux questions sont l\u00e0 pour vous aider.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/optionstogrow.com\/fr\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\/\" \/>\n<meta property=\"og:site_name\" content=\"Des options pour se d\u00e9velopper\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Options-To-Grow-109035218181837\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-12T08:19:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-12T13:48:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/optionstogrow.com\/wp-content\/uploads\/2022\/03\/pexels-andrew-neel-5255996.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dror Allouche\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mr_otg\" \/>\n<meta name=\"twitter:site\" content=\"@mr_otg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dror Allouche\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\\\/\"},\"author\":{\"name\":\"Dror Allouche\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#\\\/schema\\\/person\\\/7dd82164ca7481a8c2d59969d4cef9eb\"},\"headline\":\"Comment passer de la stagnation \u00e0 la cr\u00e9ation ? Essayez ces 2 questions toutes simples.\",\"datePublished\":\"2022-03-12T08:19:29+00:00\",\"dateModified\":\"2022-03-12T13:48:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\\\/\"},\"wordCount\":428,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/pexels-andrew-neel-5255996.jpg?fit=640%2C426&ssl=1\",\"keywords\":[\"Clart\u00e9\",\"Cr\u00e9ativit\u00e9\",\"D\u00e9cisions\",\"Responsabilit\u00e9\"],\"articleSection\":[\"R\u00e9flexion courte\",\"R\u00e9ussir personnellement\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\\\/\",\"url\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\\\/\",\"name\":\"Comment passer de la stagnation \u00e0 la cr\u00e9ation ? Essayez ces 2 questions toutes simples. - Des options pour se d\u00e9velopper\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/pexels-andrew-neel-5255996.jpg?fit=640%2C426&ssl=1\",\"datePublished\":\"2022-03-12T08:19:29+00:00\",\"dateModified\":\"2022-03-12T13:48:31+00:00\",\"description\":\"\u00c7a nous arrive tous. Un moment de stagnation. Le tout est de ne pas y rester. Ces deux questions sont l\u00e0 pour vous aider.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/pexels-andrew-neel-5255996.jpg?fit=640%2C426&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/pexels-andrew-neel-5255996.jpg?fit=640%2C426&ssl=1\",\"width\":640,\"height\":426,\"caption\":\"Comment passer de la stagnation \u00e0 la cr\u00e9ation ? Essayez ces 2 questions toutes simples.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment passer de la stagnation \u00e0 la cr\u00e9ation ? Essayez ces 2 questions toutes simples.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/\",\"name\":\"Des options pour se d\u00e9velopper\",\"description\":\"Acc\u00e9l\u00e9rer les r\u00e9sultats sur vos projets importants\",\"publisher\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#organization\",\"name\":\"OptionsToGrow\",\"url\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo-web-1-e1597514267714.jpg?fit=96%2C65&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo-web-1-e1597514267714.jpg?fit=96%2C65&ssl=1\",\"width\":96,\"height\":65,\"caption\":\"OptionsToGrow\"},\"image\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Options-To-Grow-109035218181837\",\"https:\\\/\\\/x.com\\\/mr_otg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#\\\/schema\\\/person\\\/7dd82164ca7481a8c2d59969d4cef9eb\",\"name\":\"Dror Allouche\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g\",\"caption\":\"Dror Allouche\"},\"description\":\"Executive who ran a 9-figure business. I left corporate at the age of 46, financially independent. I write to share my learning on how to grow your life, your career, your money.\",\"sameAs\":[\"https:\\\/\\\/optionstogrow.com\\\/\",\"https:\\\/\\\/x.com\\\/mr_otg\"],\"url\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/author\\\/optionstogrow\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment passer de la stagnation \u00e0 la cr\u00e9ation ? Essayez ces 2 questions toutes simples. - Des options pour se d\u00e9velopper","description":"\u00c7a nous arrive tous. Un moment de stagnation. Le tout est de ne pas y rester. Ces deux questions sont l\u00e0 pour vous aider.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/optionstogrow.com\/fr\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment passer de la stagnation \u00e0 la cr\u00e9ation ? Essayez ces 2 questions toutes simples. - Des options pour se d\u00e9velopper","og_description":"\u00c7a nous arrive tous. Un moment de stagnation. Le tout est de ne pas y rester. Ces deux questions sont l\u00e0 pour vous aider.","og_url":"https:\/\/optionstogrow.com\/fr\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\/","og_site_name":"Des options pour se d\u00e9velopper","article_publisher":"https:\/\/www.facebook.com\/Options-To-Grow-109035218181837","article_published_time":"2022-03-12T08:19:29+00:00","article_modified_time":"2022-03-12T13:48:31+00:00","og_image":[{"width":640,"height":426,"url":"https:\/\/optionstogrow.com\/wp-content\/uploads\/2022\/03\/pexels-andrew-neel-5255996.jpg","type":"image\/jpeg"}],"author":"Dror Allouche","twitter_card":"summary_large_image","twitter_creator":"@mr_otg","twitter_site":"@mr_otg","twitter_misc":{"\u00c9crit par":"Dror Allouche","Dur\u00e9e de lecture estim\u00e9e":"2 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/optionstogrow.com\/fr\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\/#article","isPartOf":{"@id":"https:\/\/optionstogrow.com\/fr\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\/"},"author":{"name":"Dror Allouche","@id":"https:\/\/optionstogrow.com\/fr\/#\/schema\/person\/7dd82164ca7481a8c2d59969d4cef9eb"},"headline":"Comment passer de la stagnation \u00e0 la cr\u00e9ation ? Essayez ces 2 questions toutes simples.","datePublished":"2022-03-12T08:19:29+00:00","dateModified":"2022-03-12T13:48:31+00:00","mainEntityOfPage":{"@id":"https:\/\/optionstogrow.com\/fr\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\/"},"wordCount":428,"commentCount":0,"publisher":{"@id":"https:\/\/optionstogrow.com\/fr\/#organization"},"image":{"@id":"https:\/\/optionstogrow.com\/fr\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2022\/03\/pexels-andrew-neel-5255996.jpg?fit=640%2C426&ssl=1","keywords":["Clart\u00e9","Cr\u00e9ativit\u00e9","D\u00e9cisions","Responsabilit\u00e9"],"articleSection":["R\u00e9flexion courte","R\u00e9ussir personnellement"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/optionstogrow.com\/fr\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/optionstogrow.com\/fr\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\/","url":"https:\/\/optionstogrow.com\/fr\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\/","name":"Comment passer de la stagnation \u00e0 la cr\u00e9ation ? Essayez ces 2 questions toutes simples. - Des options pour se d\u00e9velopper","isPartOf":{"@id":"https:\/\/optionstogrow.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/optionstogrow.com\/fr\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\/#primaryimage"},"image":{"@id":"https:\/\/optionstogrow.com\/fr\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2022\/03\/pexels-andrew-neel-5255996.jpg?fit=640%2C426&ssl=1","datePublished":"2022-03-12T08:19:29+00:00","dateModified":"2022-03-12T13:48:31+00:00","description":"\u00c7a nous arrive tous. Un moment de stagnation. Le tout est de ne pas y rester. Ces deux questions sont l\u00e0 pour vous aider.","breadcrumb":{"@id":"https:\/\/optionstogrow.com\/fr\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/optionstogrow.com\/fr\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/optionstogrow.com\/fr\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\/#primaryimage","url":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2022\/03\/pexels-andrew-neel-5255996.jpg?fit=640%2C426&ssl=1","contentUrl":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2022\/03\/pexels-andrew-neel-5255996.jpg?fit=640%2C426&ssl=1","width":640,"height":426,"caption":"Comment passer de la stagnation \u00e0 la cr\u00e9ation ? Essayez ces 2 questions toutes simples."},{"@type":"BreadcrumbList","@id":"https:\/\/optionstogrow.com\/fr\/comment-passer-de-la-stagnation-a-la-creation-essayez-ces-2-questions-toutes-simples\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/optionstogrow.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Comment passer de la stagnation \u00e0 la cr\u00e9ation ? Essayez ces 2 questions toutes simples."}]},{"@type":"WebSite","@id":"https:\/\/optionstogrow.com\/fr\/#website","url":"https:\/\/optionstogrow.com\/fr\/","name":"Des options pour se d\u00e9velopper","description":"Acc\u00e9l\u00e9rer les r\u00e9sultats sur vos projets importants","publisher":{"@id":"https:\/\/optionstogrow.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/optionstogrow.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/optionstogrow.com\/fr\/#organization","name":"OptionsToGrow","url":"https:\/\/optionstogrow.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/optionstogrow.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/07\/logo-web-1-e1597514267714.jpg?fit=96%2C65&ssl=1","contentUrl":"https:\/\/i1.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/07\/logo-web-1-e1597514267714.jpg?fit=96%2C65&ssl=1","width":96,"height":65,"caption":"OptionsToGrow"},"image":{"@id":"https:\/\/optionstogrow.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Options-To-Grow-109035218181837","https:\/\/x.com\/mr_otg"]},{"@type":"Person","@id":"https:\/\/optionstogrow.com\/fr\/#\/schema\/person\/7dd82164ca7481a8c2d59969d4cef9eb","name":"Dror Allouche","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g","caption":"Dror Allouche"},"description":"Executive who ran a 9-figure business. I left corporate at the age of 46, financially independent. I write to share my learning on how to grow your life, your career, your money.","sameAs":["https:\/\/optionstogrow.com\/","https:\/\/x.com\/mr_otg"],"url":"https:\/\/optionstogrow.com\/fr\/author\/optionstogrow\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2022\/03\/pexels-andrew-neel-5255996.jpg?fit=640%2C426&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcagkH-CR","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/posts\/2409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/comments?post=2409"}],"version-history":[{"count":4,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/posts\/2409\/revisions"}],"predecessor-version":[{"id":2421,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/posts\/2409\/revisions\/2421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/media\/2410"}],"wp:attachment":[{"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/media?parent=2409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/categories?post=2409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/tags?post=2409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}