{"id":2335,"date":"2020-09-05T07:00:16","date_gmt":"2020-09-05T07:00:16","guid":{"rendered":"https:\/\/optionstogrow.com\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/"},"modified":"2023-03-06T17:16:24","modified_gmt":"2023-03-06T17:16:24","slug":"les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre","status":"publish","type":"post","link":"https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/","title":{"rendered":"\u00ab\u00a0Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu&rsquo;ils entreprennent\u00a0\u00bb. Comment cela a transform\u00e9 ma vie et pourquoi cela peut changer la v\u00f4tre."},"content":{"rendered":"\n<p>Il y a plus de 25 ans, je faisais des courses avec ma s\u0153ur et son mari dans un centre commercial. Pendant qu&rsquo;ils faisaient les achats, je leur ai dit : \u00ab\u00a0Je vous attends au rayon librairie.\u00a0\u00bb<br><br>Je suis tomb\u00e9 par hasard sur le livre <a href=\"https:\/\/www.amazon.fr\/habitudes-ceux-r%C3%A9ussissent-quils-entreprennent\/dp\/2412022623\/ref=tmm_pap_swatch_0?_encoding=UTF8&amp;qid=&amp;sr=\" target=\"_blank\" rel=\"noreferrer noopener\">\u00ab\u00a0Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu&rsquo;ils entreprennent\u00a0\u00bb de Stephen R. Covey.<\/a><br><br>J&rsquo;avais l&rsquo;impression que ce n&rsquo;\u00e9tait que quelques minutes, mais j&rsquo;\u00e9tais coll\u00e9 au livre pendant un long moment d\u00e9j\u00e0. Je ne savais pas encore que cela allait transformer ma vie. <br><br>\u00ab\u00a0Nous devons y aller.\u00a0\u00bb<br><br>\u00ab\u00a0Quoi d\u00e9j\u00e0 ?\u00a0\u00bb<br><br>J&rsquo;h\u00e9sitais. J&rsquo;\u00e9tais \u00e0 court d&rsquo;argent. Dois-je investir dans ce livre ? Je n&rsquo;avais aucune id\u00e9e de qui \u00e9tait M. Covey. Heureusement, j&rsquo;ai pris la bonne d\u00e9cision.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"193\" height=\"293\" src=\"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2021\/10\/51fNYjmRUwL._SY291_BO1204203200_QL40_FMwebp_.webp?resize=193%2C293&#038;ssl=1\" alt=\"\" class=\"wp-image-2217\"\/><figcaption class=\"wp-element-caption\"><sup>Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu&rsquo;ils entreprennent\u00a0\u00bb. Comment cela a transform\u00e9 ma vie et pourquoi cela peut changer la v\u00f4tre.<\/sup><\/figcaption><\/figure>\n<\/div>\n\n\n<p>Depuis, je l&rsquo;ai lu une dizaine de fois dans diff\u00e9rents formats (livre\/audio) et dans diff\u00e9rentes langues. Comme je me sens en confiance avec le contenu, je l&rsquo;ai lu et \u00e9cout\u00e9 <a href=\"https:\/\/optionstogrow.com\/how-to-learn-a-new-language-with-a-full-time-job\/\" target=\"_blank\" rel=\"noreferrer noopener\">dans de nouvelles langues que je veux apprendre<\/a>: une super technique pour am\u00e9liorer son vocabulaire. <\/p>\n\n\n\n<p>J&rsquo;attribue la majeure partie de mon succ\u00e8s dans la vie <a href=\"https:\/\/optionstogrow.com\/fr\/livres-que-jai-lus\/\">aux livres<\/a>. Ils sont, sans aucun doute, mon meilleur outil pour apprendre et cr\u00e9er de nouvelles options. Je lis un livre par semaine \u00e0 un livre par mois selon la p\u00e9riode.<\/p>\n\n\n\n<p>La quantit\u00e9 m&rsquo;ouvre \u00e0 plus d&rsquo;entr\u00e9es, d&rsquo;id\u00e9es et d&rsquo;options. <a href=\"https:\/\/optionstogrow.com\/want-to-make-a-life-changing-decision-how-can-reading-help-you\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cela m&rsquo;aide \u00e0 filtrer les livres que je veux \u00e9tudier.<\/a><br>La qualit\u00e9, prendre des notes, \u00e9crire, r\u00e9fl\u00e9chir, remettre en cause le contenu, relire, m&rsquo;am\u00e8ne \u00e0 de profonds changements.<\/p>\n\n\n\n<p>Et sans aucun doute, \u00ab\u00a0Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu&rsquo;ils entreprennent\u00a0\u00bb a transform\u00e9 ma vie de fa\u00e7on spectaculaire.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-que-vous-enseignent-les-7-habitudes\">Que vous enseignent les 7 habitudes ?<\/h2>\n\n\n\n<p>Ce n&rsquo;est pas une recette rapide pour r\u00e9ussir. C&rsquo;est un cadre compos\u00e9 de 7 habitudes universelles qui aident \u00e0 grandir dans trois domaines principaux :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Votre victoire personnelle : soyez proactif, commencez par la fin en t\u00eate et faites passer les premi\u00e8res choses en premier<\/li>\n\n\n\n<li>Votre victoire publique : pensez gagnant\/gagnant, cherchez d&rsquo;abord \u00e0 comprendre, puis \u00e0 \u00eatre compris et synergisez.<\/li>\n\n\n\n<li>La derni\u00e8re partie qui englobe toutes les autres. Votre capacit\u00e9 \u00e0 investir dans votre d\u00e9veloppement continu appel\u00e9 \u00ab\u00a0Aiguisez la scie.\u00a0\u00bb par l&rsquo;auteur.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-qu-ai-je-appris\">Qu&rsquo;ai-je appris ?<\/h2>\n\n\n\n<p>Ces principes qui semblent simples sur papier sont un processus d&rsquo;apprentissage dynamique qui ne se s&rsquo;arr\u00eate jamais. C&rsquo;est peut-\u00eatre la raison pour laquelle ils ont eu un tel impact sur moi. J&rsquo;ai parfois l&rsquo;impression de les ma\u00eetriser, et \u00e0 d&rsquo;autres moments de recommencer \u00e0 z\u00e9ro.<\/p>\n\n\n\n<p>Chaque lecture m&rsquo;am\u00e8ne \u00e0 un niveau de compr\u00e9hension plus profond.<\/p>\n\n\n\n<p>Au cours des dix premi\u00e8res ann\u00e9es, j&rsquo;ai senti que je m&rsquo;\u00e9tais beaucoup (peut-\u00eatre trop) concentr\u00e9 sur ma victoire personnelle. Me concentrer sur ces principes simples mais puissants m&rsquo;a amen\u00e9 \u00e0 de nombreuses r\u00e9alisations, <a href=\"https:\/\/optionstogrow.com\/fr\/comment-obtenir-une-promotion-ce-que-jai-appris\/\" target=\"_blank\" rel=\"noreferrer noopener\">en particulier dans ma vie professionnelle.<\/a><\/p>\n\n\n\n<p>Ces dix derni\u00e8res ann\u00e9es, j&rsquo;ai beaucoup travaill\u00e9 sur \u00ab La victoire publique \u00bb. C&rsquo;est un niveau de leadership beaucoup plus complexe. Ces principes m&rsquo;aident \u00e9norm\u00e9ment \u00e0 relever les d\u00e9fis de la construction d&rsquo;une famille, \u00e0 progresser rapidement dans ma carri\u00e8re professionnelle et \u00e0 trouver la bonne harmonie entre les deux. Je crois que c&rsquo;est l&rsquo;un des d\u00e9fis les plus complexes de notre \u00e8re.<\/p>\n\n\n\n<p>Comme pour tout apprentissage, il y a une grande diff\u00e9rence entre comprendre et appliquer un concept. J&rsquo;ai fait des progr\u00e8s significatifs lorsque j&rsquo;ai \u00e9tudi\u00e9 activement Les 7 habitudes en lisant, en tenant un <a href=\"https:\/\/optionstogrow.com\/why-should-we-all-be-writers\/\" target=\"_blank\" rel=\"noreferrer noopener\">journal<\/a> et en les partageant avec mes coll\u00e8gues. <\/p>\n\n\n\n<p><a href=\"https:\/\/winning-writer-6789.ck.page\/2063ed76c8\" target=\"_blank\" rel=\"noreferrer noopener\">D\u00e9couvrez mon Guide ressources : Les 11 livres qui ont le plus influenc\u00e9 ma carri\u00e8re. (Y compris mon pr\u00e9f\u00e9r\u00e9 de toutes les cat\u00e9gories)<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-les-7-habitudes-qu-est-ce-que-j-applique\">Les 7 habitudes : qu&rsquo;est-ce que j&rsquo;applique ?<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2023\/03\/Allouche_Dror_-49-da.jpg?resize=768%2C548&#038;ssl=1\" alt=\"\" class=\"wp-image-3745\" width=\"768\" height=\"548\" srcset=\"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2023\/03\/Allouche_Dror_-49-da-scaled.jpg?resize=1024%2C731&amp;ssl=1 1024w, https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2023\/03\/Allouche_Dror_-49-da-scaled.jpg?resize=300%2C214&amp;ssl=1 300w, https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2023\/03\/Allouche_Dror_-49-da-scaled.jpg?resize=768%2C549&amp;ssl=1 768w, https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2023\/03\/Allouche_Dror_-49-da-scaled.jpg?resize=1536%2C1097&amp;ssl=1 1536w, https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2023\/03\/Allouche_Dror_-49-da-scaled.jpg?resize=2048%2C1463&amp;ssl=1 2048w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\"><sup>Photo de Dominic B\u00fcttner<\/sup><\/figcaption><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"soyez-proactif-deux-idees-principales-sont-devenues-assez-automatiques-pour-moi\">Soyez proactif : Deux id\u00e9es principales sont devenues assez automatiques pour moi.<\/h3>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Entre ce qui vous arrive et votre r\u00e9ponse, il y a un espace. Cet espace est votre libert\u00e9 de choisir d&rsquo;\u00eatre r\u00e9actif (je suis une victime) ou proactif (je suis 100% responsable).<br>Ce concept m&rsquo;a beaucoup touch\u00e9. J&rsquo;y r\u00e9fl\u00e9chis souvent dans mon journal pour m&rsquo;aider \u00e0 voir les situations sous un angle diff\u00e9rent. C&rsquo;est tellement facile de d\u00e9river et de rejeter la responsabilit\u00e9 sur les autres : mes enfants, ma femme, mes coll\u00e8gues, mon associ\u00e9. Assumer la responsabilit\u00e9 \u00e0 100% m&rsquo;a aid\u00e9 \u00e0 r\u00e9soudre des centaines de d\u00e9fis et \u00e0 grandir en tant que personne.<\/li>\n\n\n\n<li>Votre cercle d&rsquo;influence versus votre cercle de pr\u00e9occupation. Ce concept fonctionne pour moi comme un excellent filtre pour rester concentr\u00e9 et responsable. Il dirige mon \u00e9nergie sur des probl\u00e8mes que je peux influencer. Plus je l&rsquo;applique, plus mon cercle d&rsquo;influence s&rsquo;\u00e9tend.<\/li>\n<\/ol>\n\n\n\n<p>Aujourd&rsquo;hui, au sein du comit\u00e9 ex\u00e9cutif d&rsquo;une entreprise internationale,<br>J&rsquo;influence des d\u00e9cisions qui \u00e9taient hors de ma port\u00e9e il y a encore deux ans. Je suis arriv\u00e9 \u00e0 cette situation gr\u00e2ce \u00e0 mon approche disciplin\u00e9e, en me concentrant sur les d\u00e9fis dans mon cercle d&rsquo;influence.<\/p>\n\n\n\n<p>Nous avons chacun beaucoup plus d&rsquo;influence que nous ne pouvons l&rsquo;imaginer, mais la plupart du temps, nous perdons notre temps pr\u00e9cieux sur les mauvaises pr\u00e9occupations. Cela consomme notre bande passante \u00e9motionnelle et physique. Cela affecte notre capacit\u00e9 \u00e0 avoir un impact sur les choses importantes que nous pouvons changer.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"commencez-avec-l-objectif-final-en-tete\">Commencez avec l&rsquo;objectif final en t\u00eate. <\/h3>\n\n\n\n<p><a rel=\"noreferrer noopener\" href=\"https:\/\/optionstogrow.com\/earn-more-spend-less-live-more-dont-live-on-a-budget-live-on-your-frame\/\" target=\"_blank\">(see, Earn more, spend less, live more. Don\u2019t live on a budget, live on your frame.)<\/a><\/p>\n\n\n\n<p>En tant que leader, j&rsquo;ai l&rsquo;habitude de construire mes pr\u00e9visions, mon budget, mon prochain plan triennal. Bien que je travaille professionnellement sur ces processus, il n&rsquo;est pas facile de les transf\u00e9rer dans ma vie priv\u00e9e. M. Covey m&rsquo;a aid\u00e9 \u00e0 r\u00e9fl\u00e9chir \u00e0 mes r\u00f4les de mani\u00e8re plus  d\u00e9taill\u00e9e et \u00e0 partir de diff\u00e9rentes dimensions.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>R\u00f4les : En tant que mari, en tant que p\u00e8re, en tant que fr\u00e8re, en tant que fils, en tant qu&rsquo;ami, en tant que chef d&rsquo;entreprise\u2026<\/li>\n\n\n\n<li>Dimensions : physique, \u00e9motionnelle, spirituelle et mentale.<\/li>\n<\/ul>\n\n\n\n<p>Un excellent livre qui m&rsquo;a aid\u00e9 dans cet exercice est <a href=\"https:\/\/www.amazon.com\/Living-Forward-Proven-Plan-Drifting\/dp\/0801018846\/ref=tmm_pap_swatch_0?_encoding=UTF8&amp;qid=1598814440&amp;sr=1-1\" target=\"_blank\" rel=\"noreferrer noopener\">Living Forward: A Proven Plan to Stop Drifting and Get the Life You Want.<\/a> ll se concentre sur la seconde habitude. (Commencez avec l&rsquo;objectif final en t\u00eate.)<br><br>J&rsquo;ai construit mon premier plan de vie d\u00e9taill\u00e9 en 2016. Je le lis souvent et le mets \u00e0 jour chaque ann\u00e9e. Rester connect\u00e9 \u00e0 ma vue d&rsquo;ensemble me donne le sentiment de dessiner ma vie avec intention. <a href=\"https:\/\/optionstogrow.com\/fr\/comment-construire-son-projet-de-vie\/\" target=\"_blank\" rel=\"noreferrer noopener\">Voir ici. <\/a><br><br><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/08\/7_habits_decision-making_matrix-1.png?resize=517%2C519&#038;ssl=1\" alt=\"Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu'ils entreprennent\u201d. Comment cela a transform\u00e9 ma vie et pourquoi cela peut changer la v\u00f4tre.\" class=\"wp-image-2105\" width=\"517\" height=\"519\" srcset=\"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/08\/7_habits_decision-making_matrix-1.png?w=898&amp;ssl=1 898w, https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/08\/7_habits_decision-making_matrix-1.png?resize=298%2C300&amp;ssl=1 298w, https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/08\/7_habits_decision-making_matrix-1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/08\/7_habits_decision-making_matrix-1.png?resize=768%2C773&amp;ssl=1 768w\" sizes=\"auto, (max-width: 517px) 100vw, 517px\" \/><figcaption class=\"wp-element-caption\"><sup>Ce fichier est sous licence Creative Commons Attribution-Share Alike 4.0 International.<\/sup><\/figcaption><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"une-chose-apres-l-autre\">Une chose apr\u00e8s l&rsquo;autre : <\/h3>\n\n\n\n<p>Le cadre que j&rsquo;utilise r\u00e9guli\u00e8rement est \u00ab\u00a0The Time Management Matrix\u00a0\u00bb. L&rsquo;id\u00e9e est de diviser vos activit\u00e9s en quatre quadrants en fonction de l&rsquo;urgence et de l&rsquo;importance.<br>Comme tout le monde, je peux passer tout mon temps sur la case urgente et importante. C&rsquo;est souvent confortable; les t\u00e2ches m&rsquo;arrivent. Il y a une sorte d&rsquo;adr\u00e9naline \u00e0 pouvoir r\u00e9soudre tous ces probl\u00e8mes, mais cela aide rarement les objectifs importants \u00e0 long terme.<br>Je m&rsquo;attache \u00e0 faire en sorte que mon \u00e9quipe et moi-m\u00eame donnions la priorit\u00e9 \u00e0 la deuxi\u00e8me case, \u00ab\u00a0non urgente et importante\u00a0\u00bb. Les r\u00e9sultats significatifs viennent souvent de l\u00e0. <a href=\"https:\/\/optionstogrow.com\/the-power-of-a-few-personal-writing-words\/\" target=\"_blank\" rel=\"noreferrer noopener\">Voir \u00ab\u00a0The power of a few personal writing words\u00a0\u00bb.<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"pensez-gagnant-gagnant-et-cherchez-d-abord-a-comprendre-puis-a-etre-compris\">Pensez gagnant-gagnant et Cherchez d&rsquo;abord \u00e0 comprendre, puis \u00e0 \u00eatre compris : <\/h3>\n\n\n\n<p>Ayant d\u00e9but\u00e9 ma carri\u00e8re dans <a href=\"https:\/\/optionstogrow.com\/why-sales-is-a-great-job-and-a-potential-career-accelerator\/\" target=\"_blank\" rel=\"noreferrer noopener\">la vente<\/a> , je comprends l&rsquo;importance du deal gagnant\/gagnant et la capacit\u00e9 d&rsquo;\u00e9coute. M. Covey m&rsquo;a pouss\u00e9 \u00e0 un autre niveau de compr\u00e9hension. J&rsquo;essaie de ne pas concourir pour la prochaine grande promotion. Je travaille \u00e0 la construction d&rsquo;une poche d&rsquo;excellence dans tout ce que je fais. Cela m&rsquo;aide \u00e0 viser l&rsquo;excellence et \u00e0 profiter du voyage.<\/p>\n\n\n\n<p><strong>Le concept de comprendre d&rsquo;abord<\/strong> m&rsquo;a accompagn\u00e9 dans de nombreuses situations complexes. J&rsquo;\u00e9choue encore souvent \u00e0 l&rsquo;appliquer, mais quand je le fais, je r\u00e9alise souvent des progr\u00e8s significatifs dans des environnements tr\u00e8s complexes. <\/p>\n\n\n\n<p><strong>Synergiser :<\/strong> <\/p>\n\n\n\n<p>J&rsquo;ai repris des d\u00e9partements, des divisions et parfois des entreprises \u00e0 partir de z\u00e9ro. Vous trouvez rarement l&rsquo;\u00e9quipe parfaite o\u00f9 tout le monde occupe le r\u00f4le id\u00e9al. Passer de la tension, l&rsquo;incompr\u00e9hension \u00e0 la \u00ab\u00a0coop\u00e9ration cr\u00e9ative\u00a0\u00bb d\u00e9crite par l&rsquo;auteur est une exp\u00e9rience magique qui donne des r\u00e9sultats impressionnants.<\/p>\n\n\n\n<p>Cela arrive souvent lorsqu&rsquo;un leader aide l&rsquo;\u00e9quipe \u00e0 se recentrer sur une vision collective, \u00e0 r\u00e9organiser les t\u00e2ches en fonction des forces de l&rsquo;\u00e9quipe et \u00e0 conduire une excellente ex\u00e9cution.<br>Vous ne ma\u00eetrisez jamais ce processus dans toutes les situations. M\u00eame lorsque vous atteignez la recette optimale, le contexte reste dynamique et vous pouvez rapidement repartir de z\u00e9ro. C&rsquo;est ce qui rend la vie personnelle et professionnelle si stimulante et passionnante.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"aiguisez-la-scie\">Aiguisez la scie: <\/h3>\n\n\n\n<p>Covey le d\u00e9crit comme la capacit\u00e9 de se renouveler sur les quatre dimensions : physique, \u00e9motionnelle, spirituelle et mentale.<br>Quand j&rsquo;ai commenc\u00e9 \u00e0 appliquer cette habitude avec discipline, ma vie a profond\u00e9ment chang\u00e9.<br>Il y a cinq ans, sous l&rsquo;impulsion de \u00ab <a rel=\"noreferrer noopener\" href=\"https:\/\/www.amazon.com\/Miracle-Morning-Not-So-Obvious-Guaranteed-Transform\/dp\/0979019710\/ref=tmm_pap_swatch_0?_encoding=UTF8&amp;qid=1598813655&amp;sr=1-1\" target=\"_blank\">The Miracle Morning : The Not-So-Ebvious Secret Guaranteed to Transform Your Life<\/a> \u00bb, j&rsquo;ai commenc\u00e9 \u00e0 consacrer au moins une heure par jour \u00e0 couvrir les quatre dimensions.<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p> Depuis, je me l\u00e8ve \u00e0 5h du matin et suis cette routine matinale :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Physique : Exercices respiratoires, exercices physiques.<\/li>\n\n\n\n<li>\u00c9motionnel\/spirituel : Temps de m\u00e9ditation qui int\u00e8gre la gratitude et la r\u00e9vision mentale de mes principaux objectifs.<\/li>\n\n\n\n<li>Mental : Tenir un journal et se concentrer sur un sujet d&rsquo;apprentissage. <br>D\u00e9couvrez comment construire votre routine <a href=\"https:\/\/optionstogrow.com\/how-to-start-doing-the-things-you-want-to-do\/\" target=\"_blank\" rel=\"noreferrer noopener\">ici.<\/a> <\/li>\n<\/ul>\n\n\n\n<p><\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-pourquoi-les-7-habitudes-ont-elles-transforme-ma-vie\">Pourquoi Les 7 Habitudes ont-elles transform\u00e9 ma vie ?<\/h2>\n\n\n\n<p>Le livre m&rsquo;a fourni un cadre suffisamment structur\u00e9 pour me guider mais suffisamment large pour ouvrir ma curiosit\u00e9 vers un d\u00e9veloppement continu. Le cadre m&rsquo;a aid\u00e9 \u00e0 organiser les nouvelles connaissances aquises. La plupart des +300 livres que j&rsquo;ai lus rel\u00e8vent de l&rsquo;une des 7 habitudes. <\/p>\n\n\n\n<p>Je crois que la connaissance ne peut pas toujours nous \u00eatre enseign\u00e9e. Nous y allons lorsque nous sommes pr\u00eats et s\u00e9lectionnons \u00ab\u00a0comment\u00a0\u00bb nous voulons l&rsquo;apprendre. C&rsquo;est ce que les 7 habitudes m&rsquo;ont offert.<br><br>C&rsquo;est un syst\u00e8me de principes, \u00e9prouv\u00e9s au fil du temps, qui offre de nombreuses options pour mieux g\u00e9rer les d\u00e9fis de la vie. Ce livre a et continue de changer ma vie. Il m&rsquo;aide \u00e0 dessiner intentionnellement mon pr\u00e9sent et \u00e0 influencer mon avenir. Je serai \u00e9ternellement reconnaissant \u00e0 M. Stephen R Covey pour ce cadeau.<\/p>\n\n\n\n<p><strong>Quel livre a transform\u00e9 votre vie ?<\/strong><\/p>\n\n\n\n<p>&#8212;<\/p>\n\n\n\n<p>PS: D\u00e8s que vous \u00eates pr\u00eat, voici 2 autres fa\u00e7ons dont je peux vous aider \u00e0 acc\u00e9l\u00e9rer votre croissance gr\u00e2ce au coaching :<\/p>\n\n\n\n<p>&#8211; Vous \u00eates un particulier : vous avez un penchant pour l&rsquo;action. Vous avez r\u00e9alis\u00e9 beaucoup de choses. Et pourtant vous voulez plus. <a href=\"https:\/\/calendly.com\/optionstogrow\/canweworktogether\" target=\"_blank\" rel=\"noreferrer noopener\">Connectons-nous<\/a> pour un appel gratuit et voyons si nous pouvons travailler ensemble.<\/p>\n\n\n\n<p>&#8211; Vous voulez \u00eatre coach\u00e9 sur votre lieu de travail. J&rsquo;aide les dirigeants qui r\u00e9ussissent \u00e0 devenir encore meilleurs. Et vous ne me payez que si vous r\u00e9ussissez (oui, je suis s\u00e9rieux). Curieux d&rsquo;en savoir plus. <a href=\"https:\/\/optionstogrow.com\/?page_id=3412\" target=\"_blank\" rel=\"noreferrer noopener\">Apprenez-en davantage ici.<\/a><\/p>\n\n\n\n<p><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a plus de 20 ans, je faisais des courses avec ma s\u0153ur et son mari dans un centre commercial. Pendant qu&rsquo;ils faisaient les courses, je leur ai dit : \u00ab Je vous attends dans le rayon biblioth\u00e8que \u00bb.<br \/>\nJe suis tomb\u00e9 sur \u00ab\u00a0Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu&rsquo;ils entreprennent\u00a0\u00bb de Stephen R. Covey en surplombant certains livres.<br \/>\nJ&rsquo;avais l&rsquo;impression que ce n&rsquo;\u00e9tait que quelques minutes, mais j&rsquo;\u00e9tais d\u00e9j\u00e0 pris pendant un moment, \u00ab\u00a0nous devons y aller\u00a0\u00bb. Quoi d\u00e9j\u00e0?<br \/>\nJ&rsquo;h\u00e9sitais. J&rsquo;\u00e9tais \u00e0 court d&rsquo;argent, devrais-je investir dans ce livre. Je n&rsquo;avais aucune id\u00e9e de qui \u00e9tait M. Covey. Dans un moment de clart\u00e9, j&rsquo;ai pris la bonne d\u00e9cision en achetant le livre.<\/p>\n","protected":false},"author":2,"featured_media":2107,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_wp_convertkit_post_meta":{"form":"2577560","landing_page":"","tag":"2605809","restrict_content":""},"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[85,84,79],"tags":[80,86],"class_list":{"0":"post-2335","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-blog-fr","8":"category-reussir-personnellement","9":"category-reussir-professionnellement","10":"tag-apprendre","11":"tag-livres","12":"entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu&#039;ils entreprennent&quot;. Comment cela a transform\u00e9 ma vie et pourquoi cela peut changer la v\u00f4tre. - Des options pour se d\u00e9velopper<\/title>\n<meta name=\"description\" content=\"Quel livre vous a le plus influenc\u00e9 ? Pour moi, c&#039;est &quot;Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu&#039;ils entreprennent&quot; de Stephen R. Covey. Ce livre a et continue de transformer ma vie\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu&#039;ils entreprennent&quot;. Comment cela a transform\u00e9 ma vie et pourquoi cela peut changer la v\u00f4tre. - Des options pour se d\u00e9velopper\" \/>\n<meta property=\"og:description\" content=\"Quel livre vous a le plus influenc\u00e9 ? Pour moi, c&#039;est &quot;Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu&#039;ils entreprennent&quot; de Stephen R. Covey. Ce livre a et continue de transformer ma vie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/\" \/>\n<meta property=\"og:site_name\" content=\"Des options pour se d\u00e9velopper\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Options-To-Grow-109035218181837\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-05T07:00:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-06T17:16:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/optionstogrow.com\/wp-content\/uploads\/2020\/08\/covey-book-1-e1598816864892.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"327\" \/>\n\t<meta property=\"og:image:height\" content=\"312\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dror Allouche\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mr_otg\" \/>\n<meta name=\"twitter:site\" content=\"@mr_otg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dror Allouche\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\\\/\"},\"author\":{\"name\":\"Dror Allouche\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#\\\/schema\\\/person\\\/7dd82164ca7481a8c2d59969d4cef9eb\"},\"headline\":\"\u00ab\u00a0Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu&rsquo;ils entreprennent\u00a0\u00bb. Comment cela a transform\u00e9 ma vie et pourquoi cela peut changer la v\u00f4tre.\",\"datePublished\":\"2020-09-05T07:00:16+00:00\",\"dateModified\":\"2023-03-06T17:16:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\\\/\"},\"wordCount\":1969,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/covey-book-1-e1598816864892.jpg?fit=327%2C312&ssl=1\",\"keywords\":[\"Apprendre\",\"Livres\"],\"articleSection\":[\"Blog\",\"R\u00e9ussir personnellement\",\"R\u00e9ussir professionnellement\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\\\/\",\"url\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\\\/\",\"name\":\"\\\"Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu'ils entreprennent\\\". Comment cela a transform\u00e9 ma vie et pourquoi cela peut changer la v\u00f4tre. - Des options pour se d\u00e9velopper\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/covey-book-1-e1598816864892.jpg?fit=327%2C312&ssl=1\",\"datePublished\":\"2020-09-05T07:00:16+00:00\",\"dateModified\":\"2023-03-06T17:16:24+00:00\",\"description\":\"Quel livre vous a le plus influenc\u00e9 ? Pour moi, c'est \\\"Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu'ils entreprennent\\\" de Stephen R. Covey. Ce livre a et continue de transformer ma vie\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/covey-book-1-e1598816864892.jpg?fit=327%2C312&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/covey-book-1-e1598816864892.jpg?fit=327%2C312&ssl=1\",\"width\":327,\"height\":312},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu&#8217;ils entreprennent&#8221;. Comment cela a transform\u00e9 ma vie et pourquoi cela peut changer la v\u00f4tre.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/\",\"name\":\"Des options pour se d\u00e9velopper\",\"description\":\"Acc\u00e9l\u00e9rer les r\u00e9sultats sur vos projets importants\",\"publisher\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#organization\",\"name\":\"OptionsToGrow\",\"url\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo-web-1-e1597514267714.jpg?fit=96%2C65&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/optionstogrow.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo-web-1-e1597514267714.jpg?fit=96%2C65&ssl=1\",\"width\":96,\"height\":65,\"caption\":\"OptionsToGrow\"},\"image\":{\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Options-To-Grow-109035218181837\",\"https:\\\/\\\/x.com\\\/mr_otg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/#\\\/schema\\\/person\\\/7dd82164ca7481a8c2d59969d4cef9eb\",\"name\":\"Dror Allouche\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g\",\"caption\":\"Dror Allouche\"},\"description\":\"Executive who ran a 9-figure business. I left corporate at the age of 46, financially independent. I write to share my learning on how to grow your life, your career, your money.\",\"sameAs\":[\"https:\\\/\\\/optionstogrow.com\\\/\",\"https:\\\/\\\/x.com\\\/mr_otg\"],\"url\":\"https:\\\/\\\/optionstogrow.com\\\/fr\\\/author\\\/optionstogrow\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu'ils entreprennent\". Comment cela a transform\u00e9 ma vie et pourquoi cela peut changer la v\u00f4tre. - Des options pour se d\u00e9velopper","description":"Quel livre vous a le plus influenc\u00e9 ? Pour moi, c'est \"Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu'ils entreprennent\" de Stephen R. Covey. Ce livre a et continue de transformer ma vie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/","og_locale":"fr_FR","og_type":"article","og_title":"\"Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu'ils entreprennent\". Comment cela a transform\u00e9 ma vie et pourquoi cela peut changer la v\u00f4tre. - Des options pour se d\u00e9velopper","og_description":"Quel livre vous a le plus influenc\u00e9 ? Pour moi, c'est \"Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu'ils entreprennent\" de Stephen R. Covey. Ce livre a et continue de transformer ma vie","og_url":"https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/","og_site_name":"Des options pour se d\u00e9velopper","article_publisher":"https:\/\/www.facebook.com\/Options-To-Grow-109035218181837","article_published_time":"2020-09-05T07:00:16+00:00","article_modified_time":"2023-03-06T17:16:24+00:00","og_image":[{"width":327,"height":312,"url":"https:\/\/optionstogrow.com\/wp-content\/uploads\/2020\/08\/covey-book-1-e1598816864892.jpg","type":"image\/jpeg"}],"author":"Dror Allouche","twitter_card":"summary_large_image","twitter_creator":"@mr_otg","twitter_site":"@mr_otg","twitter_misc":{"\u00c9crit par":"Dror Allouche","Dur\u00e9e de lecture estim\u00e9e":"9 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/#article","isPartOf":{"@id":"https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/"},"author":{"name":"Dror Allouche","@id":"https:\/\/optionstogrow.com\/fr\/#\/schema\/person\/7dd82164ca7481a8c2d59969d4cef9eb"},"headline":"\u00ab\u00a0Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu&rsquo;ils entreprennent\u00a0\u00bb. Comment cela a transform\u00e9 ma vie et pourquoi cela peut changer la v\u00f4tre.","datePublished":"2020-09-05T07:00:16+00:00","dateModified":"2023-03-06T17:16:24+00:00","mainEntityOfPage":{"@id":"https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/"},"wordCount":1969,"commentCount":0,"publisher":{"@id":"https:\/\/optionstogrow.com\/fr\/#organization"},"image":{"@id":"https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/08\/covey-book-1-e1598816864892.jpg?fit=327%2C312&ssl=1","keywords":["Apprendre","Livres"],"articleSection":["Blog","R\u00e9ussir personnellement","R\u00e9ussir professionnellement"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/","url":"https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/","name":"\"Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu'ils entreprennent\". Comment cela a transform\u00e9 ma vie et pourquoi cela peut changer la v\u00f4tre. - Des options pour se d\u00e9velopper","isPartOf":{"@id":"https:\/\/optionstogrow.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/#primaryimage"},"image":{"@id":"https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/08\/covey-book-1-e1598816864892.jpg?fit=327%2C312&ssl=1","datePublished":"2020-09-05T07:00:16+00:00","dateModified":"2023-03-06T17:16:24+00:00","description":"Quel livre vous a le plus influenc\u00e9 ? Pour moi, c'est \"Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu'ils entreprennent\" de Stephen R. Covey. Ce livre a et continue de transformer ma vie","breadcrumb":{"@id":"https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/#primaryimage","url":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/08\/covey-book-1-e1598816864892.jpg?fit=327%2C312&ssl=1","contentUrl":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/08\/covey-book-1-e1598816864892.jpg?fit=327%2C312&ssl=1","width":327,"height":312},{"@type":"BreadcrumbList","@id":"https:\/\/optionstogrow.com\/fr\/les-7-habitudes-de-ceux-qui-realisent-tout-ce-quils-entreprennent-comment-cela-a-transforme-ma-vie-et-pourquoi-cela-peut-changer-la-votre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/optionstogrow.com\/fr\/"},{"@type":"ListItem","position":2,"name":"&#8220;Les 7 habitudes de ceux qui r\u00e9alisent tout ce qu&#8217;ils entreprennent&#8221;. Comment cela a transform\u00e9 ma vie et pourquoi cela peut changer la v\u00f4tre."}]},{"@type":"WebSite","@id":"https:\/\/optionstogrow.com\/fr\/#website","url":"https:\/\/optionstogrow.com\/fr\/","name":"Des options pour se d\u00e9velopper","description":"Acc\u00e9l\u00e9rer les r\u00e9sultats sur vos projets importants","publisher":{"@id":"https:\/\/optionstogrow.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/optionstogrow.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/optionstogrow.com\/fr\/#organization","name":"OptionsToGrow","url":"https:\/\/optionstogrow.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/optionstogrow.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/07\/logo-web-1-e1597514267714.jpg?fit=96%2C65&ssl=1","contentUrl":"https:\/\/i1.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/07\/logo-web-1-e1597514267714.jpg?fit=96%2C65&ssl=1","width":96,"height":65,"caption":"OptionsToGrow"},"image":{"@id":"https:\/\/optionstogrow.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Options-To-Grow-109035218181837","https:\/\/x.com\/mr_otg"]},{"@type":"Person","@id":"https:\/\/optionstogrow.com\/fr\/#\/schema\/person\/7dd82164ca7481a8c2d59969d4cef9eb","name":"Dror Allouche","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f371f18d5905715896612f5691584303d930845d3a4eaaaf12a1249080b6918?s=96&d=mm&r=g","caption":"Dror Allouche"},"description":"Executive who ran a 9-figure business. I left corporate at the age of 46, financially independent. I write to share my learning on how to grow your life, your career, your money.","sameAs":["https:\/\/optionstogrow.com\/","https:\/\/x.com\/mr_otg"],"url":"https:\/\/optionstogrow.com\/fr\/author\/optionstogrow\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/optionstogrow.com\/wp-content\/uploads\/2020\/08\/covey-book-1-e1598816864892.jpg?fit=327%2C312&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcagkH-BF","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/posts\/2335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/comments?post=2335"}],"version-history":[{"count":6,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/posts\/2335\/revisions"}],"predecessor-version":[{"id":3752,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/posts\/2335\/revisions\/3752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/media\/2107"}],"wp:attachment":[{"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/media?parent=2335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/categories?post=2335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/optionstogrow.com\/fr\/wp-json\/wp\/v2\/tags?post=2335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}